{"id":1270,"date":"2023-12-13T13:36:59","date_gmt":"2023-12-13T10:06:59","guid":{"rendered":"https:\/\/webmehr.com\/blog\/?p=1270"},"modified":"2023-12-13T13:36:59","modified_gmt":"2023-12-13T10:06:59","slug":"%d8%a2%db%8c%d8%a7-%d9%81%d8%b1%d9%88%d8%b4%da%af%d8%a7%d9%87-%d8%a7%db%8c%d9%86%d8%aa%d8%b1%d9%86%d8%aa%db%8c-%d9%85%d8%a7%d9%84%db%8c%d8%a7%d8%aa-%d8%af%d8%a7%d8%b1%d8%af%d8%9f","status":"publish","type":"post","link":"https:\/\/webmehr.com\/blog\/p_1270","title":{"rendered":"\u0622\u06cc\u0627 \u0641\u0631\u0648\u0634\u06af\u0627\u0647 \u0627\u06cc\u0646\u062a\u0631\u0646\u062a\u06cc \u0645\u0627\u0644\u06cc\u0627\u062a \u062f\u0627\u0631\u062f\u061f"},"content":{"rendered":"<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_83 ez-toc-wrap-right counter-hierarchy ez-toc-counter-rtl ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">\u0622\u0646\u0686\u0647 \u062f\u0631 \u0627\u06cc\u0646 \u0645\u0637\u0644\u0628 \u062e\u0648\u0627\u0647\u06cc\u062f \u062e\u0648\u0627\u0646\u062f:<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/webmehr.com\/blog\/p_1270\/#%D9%85%D8%A7%D9%84%DB%8C%D8%A7%D8%AA_%D8%A8%D8%B1_%D8%A7%D8%B1%D8%B2%D8%B4_%D8%A7%D9%81%D8%B2%D9%88%D8%AF%D9%87\" >\u0645\u0627\u0644\u06cc\u0627\u062a \u0628\u0631 \u0627\u0631\u0632\u0634 \u0627\u0641\u0632\u0648\u062f\u0647<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/webmehr.com\/blog\/p_1270\/#%D9%85%D8%A7%D9%84%DB%8C%D8%A7%D8%AA_%D8%A8%D8%B1_%D8%AF%D8%B1%D8%A2%D9%85%D8%AF\" >\u0645\u0627\u0644\u06cc\u0627\u062a \u0628\u0631 \u062f\u0631\u0622\u0645\u062f<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/webmehr.com\/blog\/p_1270\/#%D9%85%D9%87%D9%84%D8%AA%E2%80%8C%D9%87%D8%A7%DB%8C_%D9%82%D8%A7%D9%86%D9%88%D9%86%DB%8C\" >\u0645\u0647\u0644\u062a\u200c\u0647\u0627\u06cc \u0642\u0627\u0646\u0648\u0646\u06cc<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/webmehr.com\/blog\/p_1270\/#%D8%B9%D9%88%D8%A7%D9%82%D8%A8_%D8%B9%D8%AF%D9%85_%D9%BE%D8%B1%D8%AF%D8%A7%D8%AE%D8%AA_%D9%85%D8%A7%D9%84%DB%8C%D8%A7%D8%AA\" >\u0639\u0648\u0627\u0642\u0628 \u0639\u062f\u0645 \u067e\u0631\u062f\u0627\u062e\u062a \u0645\u0627\u0644\u06cc\u0627\u062a<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/webmehr.com\/blog\/p_1270\/#%D9%85%D8%B9%D8%A7%D9%81%DB%8C%D8%AA%E2%80%8C%D9%87%D8%A7%DB%8C_%D9%85%D8%A7%D9%84%DB%8C%D8%A7%D8%AA%DB%8C\" >\u0645\u0639\u0627\u0641\u06cc\u062a\u200c\u0647\u0627\u06cc \u0645\u0627\u0644\u06cc\u0627\u062a\u06cc<\/a><\/li><\/ul><\/nav><\/div>\n\n\n<div class=\"kk-star-ratings kksr-auto kksr-align-center kksr-valign-top\"\n    data-payload='{&quot;align&quot;:&quot;center&quot;,&quot;id&quot;:&quot;1270&quot;,&quot;slug&quot;:&quot;default&quot;,&quot;valign&quot;:&quot;top&quot;,&quot;ignore&quot;:&quot;&quot;,&quot;reference&quot;:&quot;auto&quot;,&quot;class&quot;:&quot;&quot;,&quot;count&quot;:&quot;0&quot;,&quot;legendonly&quot;:&quot;&quot;,&quot;readonly&quot;:&quot;&quot;,&quot;score&quot;:&quot;0&quot;,&quot;starsonly&quot;:&quot;&quot;,&quot;best&quot;:&quot;5&quot;,&quot;gap&quot;:&quot;5&quot;,&quot;greet&quot;:&quot;\u0628\u0647 \u0627\u06cc\u0646 \u0645\u0637\u0644\u0628 \u0627\u0645\u062a\u06cc\u0627\u0632 \u062f\u0647\u06cc\u062f&quot;,&quot;legend&quot;:&quot;0\\\/5 - (0 \u0627\u0645\u062a\u06cc\u0627\u0632)&quot;,&quot;size&quot;:&quot;24&quot;,&quot;title&quot;:&quot;\u0622\u06cc\u0627 \u0641\u0631\u0648\u0634\u06af\u0627\u0647 \u0627\u06cc\u0646\u062a\u0631\u0646\u062a\u06cc \u0645\u0627\u0644\u06cc\u0627\u062a \u062f\u0627\u0631\u062f\u061f&quot;,&quot;width&quot;:&quot;0&quot;,&quot;_legend&quot;:&quot;{score}\\\/{best} - ({count} {votes})&quot;,&quot;font_factor&quot;:&quot;1.25&quot;}'>\n            \n<div class=\"kksr-stars\">\n    \n<div class=\"kksr-stars-inactive\">\n            <div class=\"kksr-star\" data-star=\"1\" style=\"padding-left: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"2\" style=\"padding-left: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"3\" style=\"padding-left: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"4\" style=\"padding-left: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"5\" style=\"padding-left: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n    <\/div>\n    \n<div class=\"kksr-stars-active\" style=\"width: 0px;\">\n            <div class=\"kksr-star\" style=\"padding-left: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-left: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-left: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-left: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-left: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n    <\/div>\n<\/div>\n                \n\n<div class=\"kksr-legend\" style=\"font-size: 19.2px;\">\n            <span class=\"kksr-muted\">\u0628\u0647 \u0627\u06cc\u0646 \u0645\u0637\u0644\u0628 \u0627\u0645\u062a\u06cc\u0627\u0632 \u062f\u0647\u06cc\u062f<\/span>\n    <\/div>\n    <\/div>\n<p style=\"text-align: justify\">\n<p style=\"text-align: justify\">\u0641\u0631\u0648\u0634\u06af\u0627\u0647 \u0627\u06cc\u0646\u062a\u0631\u0646\u062a\u06cc \u0645\u0627\u0644\u06cc\u0627\u062a \u062f\u0627\u0631\u062f. \u0637\u0628\u0642 \u0642\u0648\u0627\u0646\u06cc\u0646 \u0645\u0627\u0644\u06cc\u0627\u062a\u06cc \u0627\u06cc\u0631\u0627\u0646\u060c \u062a\u0645\u0627\u0645\u06cc \u06a9\u0633\u0628 \u0648 \u06a9\u0627\u0631\u0647\u0627\u06cc \u0627\u06cc\u0646\u062a\u0631\u0646\u062a\u06cc \u0627\u0639\u0645 \u0627\u0632 \u0627\u0641\u0631\u0627\u062f \u062d\u0642\u06cc\u0642\u06cc \u0648 \u062d\u0642\u0648\u0642\u06cc \u0645\u0644\u0632\u0645 \u0628\u0647 \u067e\u0631\u062f\u0627\u062e\u062a \u0645\u0627\u0644\u06cc\u0627\u062a \u0647\u0633\u062a\u0646\u062f. \u0627\u06cc\u0646 \u0645\u0627\u0644\u06cc\u0627\u062a \u0628\u0631 \u0627\u0633\u0627\u0633 \u0645\u06cc\u0632\u0627\u0646 \u062f\u0631\u0622\u0645\u062f \u0641\u0631\u0648\u0634\u06af\u0627\u0647 \u0627\u06cc\u0646\u062a\u0631\u0646\u062a\u06cc \u0645\u062d\u0627\u0633\u0628\u0647 \u0645\u06cc\u200c\u0634\u0648\u062f.<\/p>\n<p style=\"text-align: justify\"><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter  wp-image-1135\" src=\"https:\/\/webmehr.com\/blog\/wp-content\/uploads\/2023\/12\/Store-tax-300x150.jpg\" alt=\"\" width=\"482\" height=\"241\" srcset=\"https:\/\/webmehr.com\/blog\/wp-content\/uploads\/2023\/12\/Store-tax-300x150.jpg 300w, https:\/\/webmehr.com\/blog\/wp-content\/uploads\/2023\/12\/Store-tax-768x384.jpg 768w, https:\/\/webmehr.com\/blog\/wp-content\/uploads\/2023\/12\/Store-tax.jpg 800w\" sizes=\"(max-width: 482px) 100vw, 482px\" \/><\/p>\n<p style=\"text-align: justify\"><span style=\"color: #008080\">\u0645\u0627\u0644\u06cc\u0627\u062a \u0641\u0631\u0648\u0634\u06af\u0627\u0647 \u0627\u06cc\u0646\u062a\u0631\u0646\u062a\u06cc \u0627\u0632 \u062f\u0648 \u0645\u0646\u0628\u0639 \u0627\u0635\u0644\u06cc \u062a\u0623\u0645\u06cc\u0646 \u0645\u06cc\u200c\u0634\u0648\u062f:<\/span><\/p>\n<h2 style=\"text-align: justify\"><span class=\"ez-toc-section\" id=\"%D9%85%D8%A7%D9%84%DB%8C%D8%A7%D8%AA_%D8%A8%D8%B1_%D8%A7%D8%B1%D8%B2%D8%B4_%D8%A7%D9%81%D8%B2%D9%88%D8%AF%D9%87\"><\/span><span style=\"color: #003366;font-size: 12pt\">\u0645\u0627\u0644\u06cc\u0627\u062a \u0628\u0631 \u0627\u0631\u0632\u0634 \u0627\u0641\u0632\u0648\u062f\u0647<\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p style=\"text-align: justify\">\u0645\u0627\u0644\u06cc\u0627\u062a \u0628\u0631 \u0627\u0631\u0632\u0634 \u0627\u0641\u0632\u0648\u062f\u0647 \u06cc\u06a9 \u0645\u0627\u0644\u06cc\u0627\u062a \u063a\u06cc\u0631\u0645\u0633\u062a\u0642\u06cc\u0645 \u0627\u0633\u062a \u06a9\u0647 \u0628\u0631 \u0627\u0631\u0632\u0634 \u06a9\u0627\u0644\u0627 \u06cc\u0627 \u062e\u062f\u0645\u0627\u062a\u06cc \u06a9\u0647 \u0628\u0647 \u0645\u0635\u0631\u0641\u200c\u06a9\u0646\u0646\u062f\u0647 \u0646\u0647\u0627\u06cc\u06cc \u0641\u0631\u0648\u062e\u062a\u0647 \u0645\u06cc\u200c\u0634\u0648\u062f\u060c \u0627\u0639\u0645\u0627\u0644 \u0645\u06cc\u200c\u0634\u0648\u062f. \u062f\u0631 \u0648\u0627\u0642\u0639\u060c \u0627\u06cc\u0646 \u0645\u0627\u0644\u06cc\u0627\u062a \u062a\u0648\u0633\u0637 \u062a\u0648\u0644\u06cc\u062f\u06a9\u0646\u0646\u062f\u0647 \u06cc\u0627 \u0641\u0631\u0648\u0634\u0646\u062f\u0647 \u06a9\u0627\u0644\u0627 \u06cc\u0627 \u062e\u062f\u0645\u0627\u062a \u0627\u0632 \u062e\u0631\u06cc\u062f\u0627\u0631 \u062f\u0631\u06cc\u0627\u0641\u062a \u0645\u06cc\u200c\u0634\u0648\u062f \u0648 \u0633\u067e\u0633 \u0628\u0647 \u0627\u062f\u0627\u0631\u0647 \u0627\u0645\u0648\u0631 \u0645\u0627\u0644\u06cc\u0627\u062a\u06cc \u067e\u0631\u062f\u0627\u062e\u062a \u0645\u06cc\u200c\u0634\u0648\u062f.<br \/>\n\u0646\u0631\u062e \u0645\u0627\u0644\u06cc\u0627\u062a \u0628\u0631 \u0627\u0631\u0632\u0634 \u0627\u0641\u0632\u0648\u062f\u0647 \u062f\u0631 \u0627\u06cc\u0631\u0627\u0646 \u06f9 \u062f\u0631\u0635\u062f \u0627\u0633\u062a. \u0627\u06cc\u0646 \u0628\u062f\u0627\u0646 \u0645\u0639\u0646\u0627\u0633\u062a \u06a9\u0647 \u0627\u06af\u0631 \u06cc\u06a9 \u0641\u0631\u0648\u0634\u06af\u0627\u0647 \u0627\u06cc\u0646\u062a\u0631\u0646\u062a\u06cc \u06cc\u06a9 \u06a9\u0627\u0644\u0627 \u06cc\u0627 \u062e\u062f\u0645\u062a \u0631\u0627 \u0628\u0647 \u0642\u06cc\u0645\u062a \u06f1\u06f0\u06f0 \u0647\u0632\u0627\u0631 \u062a\u0648\u0645\u0627\u0646 \u0628\u0647 \u0641\u0631\u0648\u0634 \u0628\u0631\u0633\u0627\u0646\u062f\u060c \u0628\u0627\u06cc\u062f \u06f9 \u0647\u0632\u0627\u0631 \u062a\u0648\u0645\u0627\u0646 \u0645\u0627\u0644\u06cc\u0627\u062a \u0628\u0631 \u0627\u0631\u0632\u0634 \u0627\u0641\u0632\u0648\u062f\u0647 \u0627\u0632 \u062e\u0631\u06cc\u062f\u0627\u0631 \u062f\u0631\u06cc\u0627\u0641\u062a \u06a9\u0646\u062f \u0648 \u0628\u0647 \u0627\u062f\u0627\u0631\u0647 \u0627\u0645\u0648\u0631 \u0645\u0627\u0644\u06cc\u0627\u062a\u06cc \u067e\u0631\u062f\u0627\u062e\u062a \u06a9\u0646\u062f.<\/p>\n<p style=\"text-align: justify\">\n<h2 style=\"text-align: justify\"><span class=\"ez-toc-section\" id=\"%D9%85%D8%A7%D9%84%DB%8C%D8%A7%D8%AA_%D8%A8%D8%B1_%D8%AF%D8%B1%D8%A2%D9%85%D8%AF\"><\/span><span style=\"font-size: 12pt;color: #003366\">\u0645\u0627\u0644\u06cc\u0627\u062a \u0628\u0631 \u062f\u0631\u0622\u0645\u062f<\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p style=\"text-align: justify\">\u0645\u0627\u0644\u06cc\u0627\u062a \u0628\u0631 \u062f\u0631\u0622\u0645\u062f \u06cc\u06a9 \u0645\u0627\u0644\u06cc\u0627\u062a \u0645\u0633\u062a\u0642\u06cc\u0645 \u0627\u0633\u062a \u06a9\u0647 \u0628\u0631 \u0633\u0648\u062f \u06a9\u0633\u0628 \u0648 \u06a9\u0627\u0631 \u0627\u0639\u0645\u0627\u0644 \u0645\u06cc\u200c\u0634\u0648\u062f. \u0633\u0648\u062f \u06a9\u0633\u0628 \u0648 \u06a9\u0627\u0631 \u0628\u0647 \u062a\u0641\u0627\u0648\u062a \u0628\u06cc\u0646 \u062f\u0631\u0622\u0645\u062f \u0648 \u0647\u0632\u06cc\u0646\u0647\u200c\u0647\u0627\u06cc \u06a9\u0633\u0628 \u0648 \u06a9\u0627\u0631 \u06af\u0641\u062a\u0647 \u0645\u06cc\u200c\u0634\u0648\u062f.<br \/>\n<span style=\"color: #008080\">\u0646\u0631\u062e \u0645\u0627\u0644\u06cc\u0627\u062a \u0628\u0631 \u062f\u0631\u0622\u0645\u062f \u062f\u0631 \u0627\u06cc\u0631\u0627\u0646 \u0628\u0631\u0627\u06cc \u0627\u0634\u062e\u0627\u0635 \u062d\u0642\u06cc\u0642\u06cc \u062f\u0631 \u0633\u0627\u0644 \u06f1\u06f4\u06f0\u06f1 \u0628\u0647 \u0634\u0631\u062d \u0632\u06cc\u0631 \u0627\u0633\u062a:<\/span><br \/>\n\u2022 \u062a\u0627 \u06f1.\u06f5 \u0645\u06cc\u0644\u06cc\u0627\u0631\u062f \u062a\u0648\u0645\u0627\u0646: \u06f1\u06f5 \u062f\u0631\u0635\u062f<br \/>\n\u2022 \u0627\u0632 \u06f1.\u06f5 \u062a\u0627 \u06f3 \u0645\u06cc\u0644\u06cc\u0627\u0631\u062f \u062a\u0648\u0645\u0627\u0646: \u06f2\u06f5 \u062f\u0631\u0635\u062f<br \/>\n\u2022 \u0627\u0632 \u06f3 \u062a\u0627 \u06f5 \u0645\u06cc\u0644\u06cc\u0627\u0631\u062f \u062a\u0648\u0645\u0627\u0646: \u06f3\u06f0 \u062f\u0631\u0635\u062f<br \/>\n\u2022 \u0627\u0632 \u06f5 \u062a\u0627 \u06f1\u06f0 \u0645\u06cc\u0644\u06cc\u0627\u0631\u062f \u062a\u0648\u0645\u0627\u0646: \u06f3\u06f5 \u062f\u0631\u0635\u062f<br \/>\n\u2022 \u0628\u06cc\u0634 \u0627\u0632 \u06f1\u06f0 \u0645\u06cc\u0644\u06cc\u0627\u0631\u062f \u062a\u0648\u0645\u0627\u0646: \u06f4\u06f0 \u062f\u0631\u0635\u062f<br \/>\n\u0628\u0631\u0627\u06cc \u0645\u062d\u0627\u0633\u0628\u0647 \u0645\u0627\u0644\u06cc\u0627\u062a \u0628\u0631 \u062f\u0631\u0622\u0645\u062f \u0641\u0631\u0648\u0634\u06af\u0627\u0647 \u0627\u06cc\u0646\u062a\u0631\u0646\u062a\u06cc\u060c \u0628\u0627\u06cc\u062f \u0633\u0648\u062f \u06a9\u0633\u0628 \u0648 \u06a9\u0627\u0631 \u0631\u0627 \u0628\u0627 \u0646\u0631\u062e \u0645\u0627\u0644\u06cc\u0627\u062a \u0645\u0631\u0628\u0648\u0637\u0647 \u0636\u0631\u0628 \u06a9\u0631\u062f.<\/p>\n<h2 style=\"text-align: justify\">\n<span style=\"color: #003366;font-size: 12pt\">\u0645\u0647\u0644\u062a\u200c\u0647\u0627\u06cc \u0642\u0627\u0646\u0648\u0646\u06cc<\/span><\/h2>\n<p style=\"text-align: justify\">\u0635\u0627\u062d\u0628\u0627\u0646 \u0641\u0631\u0648\u0634\u06af\u0627\u0647\u200c\u0647\u0627\u06cc \u0627\u06cc\u0646\u062a\u0631\u0646\u062a\u06cc \u0628\u0627\u06cc\u062f \u062d\u062f\u0627\u06a9\u062b\u0631 \u062a\u0627 \u06f4 \u0645\u0627\u0647 \u067e\u0633 \u0627\u0632 \u0634\u0631\u0648\u0639 \u0641\u0639\u0627\u0644\u06cc\u062a \u062e\u0648\u062f\u060c \u0627\u0642\u062f\u0627\u0645 \u0628\u0647 \u062a\u0634\u06a9\u06cc\u0644 \u067e\u0631\u0648\u0646\u062f\u0647 \u0645\u0627\u0644\u06cc\u0627\u062a\u06cc \u06a9\u0646\u0646\u062f. \u0627\u0641\u0631\u0627\u062f \u062d\u0642\u06cc\u0642\u06cc \u062a\u0627 \u0622\u062e\u0631 \u062e\u0631\u062f\u0627\u062f \u0645\u0627\u0647 \u0633\u0627\u0644 \u0628\u0639\u062f \u0648 \u0627\u0641\u0631\u0627\u062f \u062d\u0642\u0648\u0642\u06cc \u0637\u06cc \u0645\u062f\u062a \u06f4 \u0645\u0627\u0647 \u067e\u0633 \u0627\u0632 \u0627\u062a\u0645\u0627\u0645 \u0633\u0627\u0644 \u0627\u0642\u062a\u0635\u0627\u062f\u06cc \u0641\u0631\u0635\u062a \u062f\u0627\u0631\u0646\u062f \u062a\u0627 \u0627\u0638\u0647\u0627\u0631\u0646\u0627\u0645\u0647 \u0645\u0627\u0644\u06cc\u0627\u062a\u06cc \u062e\u0648\u062f \u0631\u0627 \u0628\u0647 \u0627\u062f\u0627\u0631\u0647 \u0627\u0645\u0648\u0631 \u0645\u0627\u0644\u06cc\u0627\u062a\u06cc \u062a\u062d\u0648\u06cc\u0644 \u062f\u0647\u0646\u062f. \u0627\u06cc\u0646 \u0627\u0638\u0647\u0627\u0631\u0646\u0627\u0645\u0647 \u0628\u0627\u06cc\u062f \u0627\u0632 \u0637\u0631\u06cc\u0642 \u0633\u0627\u0645\u0627\u0646\u0647 \u0627\u0644\u06a9\u062a\u0631\u0648\u0646\u06cc\u06a9\u06cc \u0645\u0627\u0644\u06cc \u062a\u062d\u0648\u06cc\u0644 \u062f\u0627\u062f\u0647 \u0634\u0648\u062f.<\/p>\n<h2 style=\"text-align: justify\"><span class=\"ez-toc-section\" id=\"%D8%B9%D9%88%D8%A7%D9%82%D8%A8_%D8%B9%D8%AF%D9%85_%D9%BE%D8%B1%D8%AF%D8%A7%D8%AE%D8%AA_%D9%85%D8%A7%D9%84%DB%8C%D8%A7%D8%AA\"><\/span><span style=\"color: #003366;font-size: 12pt\">\u0639\u0648\u0627\u0642\u0628 \u0639\u062f\u0645 \u067e\u0631\u062f\u0627\u062e\u062a \u0645\u0627\u0644\u06cc\u0627\u062a<\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p style=\"text-align: justify\">\u0639\u062f\u0645 \u067e\u0631\u062f\u0627\u062e\u062a \u0645\u0627\u0644\u06cc\u0627\u062a \u0641\u0631\u0648\u0634\u06af\u0627\u0647 \u0627\u06cc\u0646\u062a\u0631\u0646\u062a\u06cc \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f \u0639\u0648\u0627\u0642\u0628\u06cc \u0645\u0627\u0646\u0646\u062f \u062c\u0631\u06cc\u0645\u0647\u060c \u0645\u062d\u0631\u0648\u0645\u06cc\u062a \u0627\u0632 \u0627\u0645\u062a\u06cc\u0627\u0632\u0627\u062a \u0648\u06cc\u0698\u0647 \u0648 \u0645\u0639\u0627\u0641\u06cc\u062a\u200c\u0647\u0627\u06cc \u0645\u0627\u0644\u06cc\u0627\u062a\u06cc \u0648 \u062d\u062a\u06cc \u062a\u0639\u0637\u06cc\u0644\u06cc \u06a9\u0633\u0628 \u0648 \u06a9\u0627\u0631 \u0631\u0627 \u0628\u0647 \u062f\u0646\u0628\u0627\u0644 \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u062f.<\/p>\n<p style=\"text-align: justify\"><strong><span style=\"color: #3366ff;font-size: 12pt\">\u0646\u06a9\u0627\u062a \u0645\u0647\u0645<\/span><\/strong><br \/>\n\u2022 \u0641\u0631\u0648\u0634\u06af\u0627\u0647\u200c\u0647\u0627\u06cc \u0627\u06cc\u0646\u062a\u0631\u0646\u062a\u06cc \u0628\u0627\u06cc\u062f \u0628\u0631\u0627\u06cc \u062a\u0645\u0627\u0645\u06cc \u06a9\u0627\u0644\u0627\u0647\u0627 \u0648 \u062e\u062f\u0645\u0627\u062a \u062e\u0648\u062f\u060c \u0635\u0648\u0631\u062a\u062d\u0633\u0627\u0628 \u0635\u0627\u062f\u0631 \u06a9\u0646\u0646\u062f.<\/p>\n<p style=\"text-align: justify\">\u2022 \u0641\u0631\u0648\u0634\u06af\u0627\u0647\u200c\u0647\u0627\u06cc \u0627\u06cc\u0646\u062a\u0631\u0646\u062a\u06cc \u0628\u0627\u06cc\u062f \u0645\u0627\u0644\u06cc\u0627\u062a \u0628\u0631 <span style=\"font-size: 10pt\">\u0627\u0631\u0632\u0634 <\/span>\u0627\u0641\u0632\u0648\u062f\u0647 \u0631\u0627 \u0627\u0632 \u0645\u0634\u062a\u0631\u06cc\u0627\u0646 \u062e\u0648\u062f \u062f\u0631\u06cc\u0627\u0641\u062a \u06a9\u0646\u0646\u062f \u0648 \u0628\u0647 \u0627\u062f\u0627\u0631\u0647 \u0627\u0645\u0648\u0631 \u0645\u0627\u0644\u06cc\u0627\u062a\u06cc \u067e\u0631\u062f\u0627\u062e\u062a \u06a9\u0646\u0646\u062f.<\/p>\n<p style=\"text-align: justify\">\n\u2022 \u0641\u0631\u0648\u0634\u06af\u0627\u0647\u200c\u0647\u0627\u06cc \u0627\u06cc\u0646\u062a\u0631\u0646\u062a\u06cc \u0628\u0627\u06cc\u062f \u062f\u0631\u0622\u0645\u062f \u062e\u0648\u062f \u0631\u0627 \u0628\u0647 \u0635\u0648\u0631\u062a \u062f\u0642\u06cc\u0642 \u062f\u0631 \u0627\u0638\u0647\u0627\u0631\u0646\u0627\u0645\u0647 \u0645\u0627\u0644\u06cc\u0627\u062a\u06cc \u062e\u0648\u062f \u062b\u0628\u062a \u06a9\u0646\u0646\u062f.<\/p>\n<h2 style=\"text-align: justify\"><img decoding=\"async\" class=\"aligncenter  wp-image-1272\" src=\"https:\/\/webmehr.com\/blog\/wp-content\/uploads\/2023\/12\/download-11.png\" alt=\"\" width=\"479\" height=\"300\" \/><\/h2>\n<h2 style=\"text-align: justify\"><span class=\"ez-toc-section\" id=\"%D9%85%D8%B9%D8%A7%D9%81%DB%8C%D8%AA%E2%80%8C%D9%87%D8%A7%DB%8C_%D9%85%D8%A7%D9%84%DB%8C%D8%A7%D8%AA%DB%8C\"><\/span><span style=\"color: #003366;font-size: 12pt\">\u0645\u0639\u0627\u0641\u06cc\u062a\u200c\u0647\u0627\u06cc \u0645\u0627\u0644\u06cc\u0627\u062a\u06cc<\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p style=\"text-align: justify\"><span style=\"color: #008080\">\u0628\u0631 \u0627\u0633\u0627\u0633 \u0642\u0648\u0627\u0646\u06cc\u0646 \u0645\u0627\u0644\u06cc\u0627\u062a\u06cc \u0627\u06cc\u0631\u0627\u0646\u060c \u0628\u0631\u062e\u06cc \u0627\u0632 \u0641\u0631\u0648\u0634\u06af\u0627\u0647\u200c\u0647\u0627\u06cc \u0627\u06cc\u0646\u062a\u0631\u0646\u062a\u06cc \u0627\u0632 \u067e\u0631\u062f\u0627\u062e\u062a \u0645\u0627\u0644\u06cc\u0627\u062a \u0645\u0639\u0627\u0641 \u0647\u0633\u062a\u0646\u062f. \u0627\u06cc\u0646 \u0645\u0639\u0627\u0641\u06cc\u062a\u200c\u0647\u0627 \u0634\u0627\u0645\u0644 \u0645\u0648\u0627\u0631\u062f \u0632\u06cc\u0631 \u0645\u06cc\u200c\u0634\u0648\u062f:<\/span><\/p>\n<p style=\"text-align: justify\">\u2022 \u0641\u0631\u0648\u0634\u06af\u0627\u0647\u200c\u0647\u0627\u06cc \u0627\u06cc\u0646\u062a\u0631\u0646\u062a\u06cc \u06a9\u0647 \u062a\u0648\u0633\u0637 \u0633\u0627\u0632\u0645\u0627\u0646\u200c\u0647\u0627\u06cc \u062f\u0648\u0644\u062a\u06cc \u06cc\u0627 \u0639\u0645\u0648\u0645\u06cc \u063a\u06cc\u0631\u062f\u0648\u0644\u062a\u06cc \u0631\u0627\u0647\u200c\u0627\u0646\u062f\u0627\u0632\u06cc \u0634\u062f\u0647\u200c\u0627\u0646\u062f. \u0627\u06cc\u0646 \u0645\u0639\u0627\u0641\u06cc\u062a \u0628\u0647 \u0627\u06cc\u0646 \u062f\u0644\u06cc\u0644 \u0627\u0639\u0645\u0627\u0644 \u0645\u06cc\u200c\u0634\u0648\u062f \u06a9\u0647 \u0633\u0627\u0632\u0645\u0627\u0646\u200c\u0647\u0627\u06cc \u062f\u0648\u0644\u062a\u06cc \u0648 \u0639\u0645\u0648\u0645\u06cc \u063a\u06cc\u0631\u062f\u0648\u0644\u062a\u06cc \u0627\u0632 \u067e\u0631\u062f\u0627\u062e\u062a \u0645\u0627\u0644\u06cc\u0627\u062a \u0628\u0631 \u062f\u0631\u0622\u0645\u062f \u0645\u0639\u0627\u0641 \u0647\u0633\u062a\u0646\u062f. \u0628\u0646\u0627\u0628\u0631\u0627\u06cc\u0646\u060c \u0641\u0631\u0648\u0634\u06af\u0627\u0647\u200c\u0647\u0627\u06cc \u0627\u06cc\u0646\u062a\u0631\u0646\u062a\u06cc \u06a9\u0647 \u062a\u0648\u0633\u0637 \u0627\u06cc\u0646 \u0633\u0627\u0632\u0645\u0627\u0646\u200c\u0647\u0627 \u0631\u0627\u0647\u200c\u0627\u0646\u062f\u0627\u0632\u06cc \u0634\u062f\u0647\u200c\u0627\u0646\u062f \u0646\u06cc\u0632 \u0627\u0632 \u067e\u0631\u062f\u0627\u062e\u062a \u0645\u0627\u0644\u06cc\u0627\u062a \u0628\u0631 \u062f\u0631\u0622\u0645\u062f \u0645\u0639\u0627\u0641 \u0647\u0633\u062a\u0646\u062f.<\/p>\n<p style=\"text-align: justify\">\n\u2022 \u0641\u0631\u0648\u0634\u06af\u0627\u0647\u200c\u0647\u0627\u06cc \u0627\u06cc\u0646\u062a\u0631\u0646\u062a\u06cc \u06a9\u0647 \u0645\u062d\u0635\u0648\u0644\u0627\u062a \u0641\u0631\u0647\u0646\u06af\u06cc \u0648 \u0647\u0646\u0631\u06cc \u0631\u0627 \u0628\u0647 \u0641\u0631\u0648\u0634 \u0645\u06cc\u200c\u0631\u0633\u0627\u0646\u0646\u062f. \u0627\u06cc\u0646 \u0645\u0639\u0627\u0641\u06cc\u062a \u0628\u0647 \u0627\u06cc\u0646 \u062f\u0644\u06cc\u0644 \u0627\u0639\u0645\u0627\u0644 \u0645\u06cc\u200c\u0634\u0648\u062f \u06a9\u0647 \u0645\u062d\u0635\u0648\u0644\u0627\u062a \u0641\u0631\u0647\u0646\u06af\u06cc \u0648 \u0647\u0646\u0631\u06cc \u0627\u0632 \u067e\u0631\u062f\u0627\u062e\u062a \u0645\u0627\u0644\u06cc\u0627\u062a \u0628\u0631 \u0627\u0631\u0632\u0634 \u0627\u0641\u0632\u0648\u062f\u0647 \u0645\u0639\u0627\u0641 \u0647\u0633\u062a\u0646\u062f. \u0628\u0646\u0627\u0628\u0631\u0627\u06cc\u0646\u060c \u0641\u0631\u0648\u0634\u06af\u0627\u0647\u200c\u0647\u0627\u06cc \u0627\u06cc\u0646\u062a\u0631\u0646\u062a\u06cc \u06a9\u0647 \u0645\u062d\u0635\u0648\u0644\u0627\u062a \u0641\u0631\u0647\u0646\u06af\u06cc \u0648 \u0647\u0646\u0631\u06cc \u0631\u0627 \u0628\u0647 \u0641\u0631\u0648\u0634 \u0645\u06cc\u200c\u0631\u0633\u0627\u0646\u0646\u062f \u0646\u06cc\u0632 \u0627\u0632 \u067e\u0631\u062f\u0627\u062e\u062a \u0645\u0627\u0644\u06cc\u0627\u062a \u0628\u0631 \u0627\u0631\u0632\u0634 \u0627\u0641\u0632\u0648\u062f\u0647 \u0645\u0639\u0627\u0641 \u0647\u0633\u062a\u0646\u062f.<\/p>\n<p style=\"text-align: justify\">\u2022 \u0641\u0631\u0648\u0634\u06af\u0627\u0647\u200c\u0647\u0627\u06cc \u0627\u06cc\u0646\u062a\u0631\u0646\u062a\u06cc \u06a9\u0647 \u0645\u062d\u0635\u0648\u0644\u0627\u062a \u06a9\u0634\u0627\u0648\u0631\u0632\u06cc \u0631\u0627 \u0628\u0647 \u0641\u0631\u0648\u0634 \u0645\u06cc\u200c\u0631\u0633\u0627\u0646\u0646\u062f. \u0627\u06cc\u0646 \u0645\u0639\u0627\u0641\u06cc\u062a \u0628\u0647 \u0627\u06cc\u0646 \u062f\u0644\u06cc\u0644 \u0627\u0639\u0645\u0627\u0644 \u0645\u06cc\u200c\u0634\u0648\u062f \u06a9\u0647 \u0645\u062d\u0635\u0648\u0644\u0627\u062a \u06a9\u0634\u0627\u0648\u0631\u0632\u06cc \u0627\u0632 \u067e\u0631\u062f\u0627\u062e\u062a \u0645\u0627\u0644\u06cc\u0627\u062a \u0628\u0631 \u0627\u0631\u0632\u0634 \u0627\u0641\u0632\u0648\u062f\u0647 \u0645\u0639\u0627\u0641 \u0647\u0633\u062a\u0646\u062f. \u0628\u0646\u0627\u0628\u0631\u0627\u06cc\u0646\u060c \u0641\u0631\u0648\u0634\u06af\u0627\u0647\u200c\u0647\u0627\u06cc \u0627\u06cc\u0646\u062a\u0631\u0646\u062a\u06cc \u06a9\u0647 \u0645\u062d\u0635\u0648\u0644\u0627\u062a \u06a9\u0634\u0627\u0648\u0631\u0632\u06cc \u0631\u0627 \u0628\u0647 \u0641\u0631\u0648\u0634 \u0645\u06cc\u200c\u0631\u0633\u0627\u0646\u0646\u062f \u0646\u06cc\u0632 \u0627\u0632 \u067e\u0631\u062f\u0627\u062e\u062a \u0645\u0627\u0644\u06cc\u0627\u062a \u0628\u0631 \u0627\u0631\u0632\u0634 \u0627\u0641\u0632\u0648\u062f\u0647 \u0645\u0639\u0627\u0641 \u0647\u0633\u062a\u0646\u062f.<\/p>\n<p style=\"text-align: justify\">\u0639\u0644\u0627\u0648\u0647 \u0628\u0631 \u0627\u06cc\u0646\u060c \u0641\u0631\u0648\u0634\u06af\u0627\u0647\u200c\u0647\u0627\u06cc \u0627\u06cc\u0646\u062a\u0631\u0646\u062a\u06cc \u06a9\u0647 \u062f\u0631 \u0633\u0627\u0644 \u0627\u0648\u0644 \u0641\u0639\u0627\u0644\u06cc\u062a \u062e\u0648\u062f \u0642\u0631\u0627\u0631 \u062f\u0627\u0631\u0646\u062f\u060c \u0627\u0632 \u067e\u0631\u062f\u0627\u062e\u062a \u0645\u0627\u0644\u06cc\u0627\u062a \u0628\u0631 \u0627\u0631\u0632\u0634 \u0627\u0641\u0632\u0648\u062f\u0647 \u0645\u0639\u0627\u0641 \u0647\u0633\u062a\u0646\u062f.<\/p>\n<p style=\"text-align: justify\">\u0628\u0631\u0627\u06cc \u0628\u0647\u0631\u0647\u200c\u0645\u0646\u062f\u06cc \u0627\u0632 \u0645\u0639\u0627\u0641\u06cc\u062a\u200c\u0647\u0627\u06cc \u0645\u0627\u0644\u06cc\u0627\u062a\u06cc \u0641\u0631\u0648\u0634\u06af\u0627\u0647\u200c\u0647\u0627\u06cc \u0627\u06cc\u0646\u062a\u0631\u0646\u062a\u06cc\u060c \u0628\u0627\u06cc\u062f \u0645\u062f\u0627\u0631\u06a9 \u0648 \u0645\u0633\u062a\u0646\u062f\u0627\u062a \u0644\u0627\u0632\u0645 \u0631\u0627 \u0628\u0647 \u0627\u062f\u0627\u0631\u0647 \u0627\u0645\u0648\u0631 \u0645\u0627\u0644\u06cc\u0627\u062a\u06cc \u0627\u0631\u0627\u0626\u0647 \u06a9\u0631\u062f.<\/p>\n<p style=\"text-align: justify\"><img decoding=\"async\" class=\"aligncenter  wp-image-1271\" src=\"https:\/\/webmehr.com\/blog\/wp-content\/uploads\/2023\/12\/financial-management-300x131.jpg\" alt=\"\" width=\"384\" height=\"168\" srcset=\"https:\/\/webmehr.com\/blog\/wp-content\/uploads\/2023\/12\/financial-management-300x131.jpg 300w, https:\/\/webmehr.com\/blog\/wp-content\/uploads\/2023\/12\/financial-management-768x336.jpg 768w, https:\/\/webmehr.com\/blog\/wp-content\/uploads\/2023\/12\/financial-management.jpg 1000w\" sizes=\"(max-width: 384px) 100vw, 384px\" \/><br \/>\n<span style=\"color: #003366;font-size: 12pt\">\u0628\u0647 \u0637\u0648\u0631 \u06a9\u0644\u06cc:<\/span><br \/>\n\u0628\u0631\u0627\u06cc \u06a9\u0633\u0628 \u0627\u0637\u0644\u0627\u0639\u0627\u062a \u0628\u06cc\u0634\u062a\u0631 \u062f\u0631 \u0645\u0648\u0631\u062f \u0645\u0639\u0627\u0641\u06cc\u062a\u200c\u0647\u0627\u06cc \u0645\u0627\u0644\u06cc\u0627\u062a\u06cc \u0641\u0631\u0648\u0634\u06af\u0627\u0647\u200c\u0647\u0627\u06cc \u0627\u06cc\u0646\u062a\u0631\u0646\u062a\u06cc\u060c \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u06cc\u062f \u0628\u0647 \u0633\u0627\u06cc\u062a \u0633\u0627\u0632\u0645\u0627\u0646 \u0627\u0645\u0648\u0631 \u0645\u0627\u0644\u06cc\u0627\u062a\u06cc \u06a9\u0634\u0648\u0631 \u0645\u0631\u0627\u062c\u0639\u0647 \u06a9\u0646\u06cc\u062f.<br \/>\n\u0627\u0645\u06cc\u062f\u0648\u0627\u0631\u0645 \u0627\u06cc\u0646 \u062a\u0648\u0636\u06cc\u062d\u0627\u062a \u0628\u0631\u0627\u06cc\u062a\u0627\u0646 \u0645\u0641\u06cc\u062f \u0628\u0648\u062f\u0647 \u0628\u0627\u0634\u062f. \u0647\u0645\u0686\u0646\u06cc\u0646 \u0627\u06af\u0631 \u0642\u0635\u062f <a href=\"https:\/\/webmehr.com\/%d8%b7%d8%b1%d8%a7%d8%ad%db%8c-%d8%b3%d8%a7%db%8c%d8%aa\" data-internallinksmanager029f6b8e52c=\"1\" title=\"\u0637\u0631\u0627\u062d\u06cc \u0633\u0627\u06cc\u062a\" target=\"_blank\" rel=\"noopener\">\u0637\u0631\u0627\u062d\u06cc \u0633\u0627\u06cc\u062a<\/a> \u0641\u0631\u0648\u0634\u06af\u0627\u0647\u06cc \u062e\u0648\u062f\u062a\u0627\u0646 \u0631\u0627 \u062f\u0627\u0631\u06cc\u062f \u0645\u06cc\u062a\u0648\u0627\u0646\u062f \u0627\u0632 <strong>\u0634\u0631\u06a9\u062a <a href=\"https:\/\/webmehr.com\" data-internallinksmanager029f6b8e52c=\"2\" title=\"\u0637\u0631\u0627\u062d\u06cc \u0648\u0628 \u0633\u0627\u06cc\u062a\" target=\"_blank\" rel=\"noopener\">\u0637\u0631\u0627\u062d\u06cc \u0648\u0628 \u0633\u0627\u06cc\u062a<\/a> \u0648 \u0633\u0626\u0648 \u0648\u0628 \u0645\u0647\u0631<\/strong> \u062f\u0631 \u0627\u06cc\u0646 \u0632\u0645\u06cc\u0646\u0647 \u06a9\u0645\u06a9 \u06af\u0631\u0641\u062a\u0647 \u0648 \u0628\u0647 \u0647\u062f\u0641 \u062e\u0648\u062f \u0628\u0631\u0633\u06cc\u062f.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0641\u0631\u0648\u0634\u06af\u0627\u0647 \u0627\u06cc\u0646\u062a\u0631\u0646\u062a\u06cc \u0645\u0627\u0644\u06cc\u0627\u062a \u062f\u0627\u0631\u062f. \u0637\u0628\u0642 \u0642\u0648\u0627\u0646\u06cc\u0646 \u0645\u0627\u0644\u06cc\u0627\u062a\u06cc \u0627\u06cc\u0631\u0627\u0646\u060c \u062a\u0645\u0627\u0645\u06cc \u06a9\u0633\u0628 \u0648 \u06a9\u0627\u0631\u0647\u0627\u06cc \u0627\u06cc\u0646\u062a\u0631\u0646\u062a\u06cc \u0627\u0639\u0645 \u0627\u0632 \u0627\u0641\u0631\u0627\u062f \u062d\u0642\u06cc\u0642\u06cc \u0648 \u062d\u0642\u0648\u0642\u06cc \u0645\u0644\u0632\u0645 \u0628\u0647 \u067e\u0631\u062f\u0627\u062e\u062a \u0645\u0627\u0644\u06cc\u0627\u062a \u0647\u0633\u062a\u0646\u062f. \u0627\u06cc\u0646 \u0645\u0627\u0644\u06cc\u0627\u062a \u0628\u0631 \u0627\u0633\u0627\u0633 \u0645\u06cc\u0632\u0627\u0646 \u062f\u0631\u0622\u0645\u062f \u0641\u0631\u0648\u0634\u06af\u0627\u0647 \u0627\u06cc\u0646\u062a\u0631\u0646\u062a\u06cc \u0645\u062d\u0627\u0633\u0628\u0647 \u0645\u06cc\u200c\u0634\u0648\u062f. \u0645\u0627\u0644\u06cc\u0627\u062a \u0641\u0631\u0648\u0634\u06af\u0627\u0647 \u0627\u06cc\u0646\u062a\u0631\u0646\u062a\u06cc \u0627\u0632 \u062f\u0648 \u0645\u0646\u0628\u0639 \u0627\u0635\u0644\u06cc \u062a\u0623\u0645\u06cc\u0646 \u0645\u06cc\u200c\u0634\u0648\u062f: \u0645\u0627\u0644\u06cc\u0627\u062a \u0628\u0631 \u0627\u0631\u0632\u0634 \u0627\u0641\u0632\u0648\u062f\u0647 \u0645\u0627\u0644\u06cc\u0627\u062a \u0628\u0631 \u0627\u0631\u0632\u0634 \u0627\u0641\u0632\u0648\u062f\u0647 \u06cc\u06a9 \u0645\u0627\u0644\u06cc\u0627\u062a \u063a\u06cc\u0631\u0645\u0633\u062a\u0642\u06cc\u0645 \u0627\u0633\u062a &hellip;<\/p>\n","protected":false},"author":2,"featured_media":1273,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[28],"tags":[],"class_list":["post-1270","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-site-management-training"],"_links":{"self":[{"href":"https:\/\/webmehr.com\/blog\/wp-json\/wp\/v2\/posts\/1270","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/webmehr.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/webmehr.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/webmehr.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/webmehr.com\/blog\/wp-json\/wp\/v2\/comments?post=1270"}],"version-history":[{"count":1,"href":"https:\/\/webmehr.com\/blog\/wp-json\/wp\/v2\/posts\/1270\/revisions"}],"predecessor-version":[{"id":1274,"href":"https:\/\/webmehr.com\/blog\/wp-json\/wp\/v2\/posts\/1270\/revisions\/1274"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/webmehr.com\/blog\/wp-json\/wp\/v2\/media\/1273"}],"wp:attachment":[{"href":"https:\/\/webmehr.com\/blog\/wp-json\/wp\/v2\/media?parent=1270"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/webmehr.com\/blog\/wp-json\/wp\/v2\/categories?post=1270"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/webmehr.com\/blog\/wp-json\/wp\/v2\/tags?post=1270"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}