{"id":1614,"date":"2024-01-13T16:49:29","date_gmt":"2024-01-13T13:19:29","guid":{"rendered":"https:\/\/webmehr.com\/blog\/?p=1614"},"modified":"2024-01-13T16:49:29","modified_gmt":"2024-01-13T13:19:29","slug":"%d8%a7%d9%84%da%af%d9%88%d8%b1%db%8c%d8%aa%d9%85-%d9%be%d9%86%da%af%d9%88%d8%a6%d9%86-%d9%85%d8%a8%d8%a7%d8%b1%d8%b2%d9%87-%d8%a8%d8%a7-%d9%84%db%8c%d9%86%da%a9%d9%87%d8%a7%db%8c-%d8%a7","status":"publish","type":"post","link":"https:\/\/webmehr.com\/blog\/p_1614","title":{"rendered":"\u0627\u0644\u06af\u0648\u0631\u06cc\u062a\u0645 \u067e\u0646\u06af\u0648\u0626\u0646: \u0645\u0628\u0627\u0631\u0632\u0647 \u0628\u0627 \u0644\u06cc\u0646\u06a9\u200c\u0647\u0627\u06cc \u0627\u0633\u067e\u0645 \u0648 \u0627\u0631\u062a\u0642\u0627\u06cc \u0631\u062a\u0628\u0647\u200c\u0628\u0646\u062f\u06cc \u0637\u0628\u06cc\u0639\u06cc \u062c\u0633\u062a\u062c\u0648"},"content":{"rendered":"<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_83 ez-toc-wrap-right counter-hierarchy ez-toc-counter-rtl ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">\u0622\u0646\u0686\u0647 \u062f\u0631 \u0627\u06cc\u0646 \u0645\u0637\u0644\u0628 \u062e\u0648\u0627\u0647\u06cc\u062f \u062e\u0648\u0627\u0646\u062f:<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/webmehr.com\/blog\/p_1614\/#%D9%85%D9%82%D8%AF%D9%85%D9%87\" >\u0645\u0642\u062f\u0645\u0647<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/webmehr.com\/blog\/p_1614\/#%D9%86%D8%AD%D9%88%D9%87%E2%80%8C%DB%8C_%D8%B9%D9%85%D9%84%DA%A9%D8%B1%D8%AF_%D9%BE%D9%86%DA%AF%D9%88%D8%A6%D9%86\" >\u0646\u062d\u0648\u0647\u200c\u06cc \u0639\u0645\u0644\u06a9\u0631\u062f \u067e\u0646\u06af\u0648\u0626\u0646<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/webmehr.com\/blog\/p_1614\/#%D8%B4%D9%86%D8%A7%D8%B3%D8%A7%DB%8C%DB%8C_%D9%88%D8%A8%E2%80%8C%D8%B3%D8%A7%DB%8C%D8%AA%E2%80%8C%D9%87%D8%A7%DB%8C_%D8%A8%D8%A7_%D9%85%D8%AD%D8%AA%D9%88%D8%A7%DB%8C_%D8%A7%D8%B3%D9%BE%D9%85\" >\u0634\u0646\u0627\u0633\u0627\u06cc\u06cc \u0648\u0628\u200c\u0633\u0627\u06cc\u062a\u200c\u0647\u0627\u06cc \u0628\u0627 \u0645\u062d\u062a\u0648\u0627\u06cc \u0627\u0633\u067e\u0645<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/webmehr.com\/blog\/p_1614\/#%D8%B9%D9%84%D8%A7%D8%A6%D9%85_%D9%82%D8%B1%D9%85%D8%B2_%D8%A8%D8%B1%D8%A7%DB%8C_%D8%B3%D8%A7%DB%8C%D8%AA_%D8%B4%D9%85%D8%A7_%D9%87%D8%B4%D8%AF%D8%A7%D8%B1%D9%87%D8%A7_%D8%A8%D8%B1%D8%A7%DB%8C_%D8%AC%D9%84%D9%88%DA%AF%DB%8C%D8%B1%DB%8C_%D8%A7%D8%B2_%D8%AC%D8%B1%DB%8C%D9%85%D9%87_Penguin_%DA%AF%D9%88%DA%AF%D9%84\" >\u0639\u0644\u0627\u0626\u0645 \u0642\u0631\u0645\u0632 \u0628\u0631\u0627\u06cc \u0633\u0627\u06cc\u062a \u0634\u0645\u0627: \u0647\u0634\u062f\u0627\u0631\u0647\u0627 \u0628\u0631\u0627\u06cc \u062c\u0644\u0648\u06af\u06cc\u0631\u06cc \u0627\u0632 \u062c\u0631\u06cc\u0645\u0647 Penguin \u06af\u0648\u06af\u0644<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/webmehr.com\/blog\/p_1614\/#%D8%AA%D8%BA%DB%8C%DB%8C%D8%B1_%D9%86%D8%A7%DA%AF%D9%87%D8%A7%D9%86%DB%8C_%D8%AF%D8%B1_%D8%B1%D8%AA%D8%A8%D9%87_%D8%A8%D9%86%D8%AF%DB%8C_%D8%B3%D8%A7%DB%8C%D8%AA_%D8%B4%D9%85%D8%A7\" >\u062a\u063a\u06cc\u06cc\u0631 \u0646\u0627\u06af\u0647\u0627\u0646\u06cc \u062f\u0631 \u0631\u062a\u0628\u0647 \u0628\u0646\u062f\u06cc \u0633\u0627\u06cc\u062a \u0634\u0645\u0627<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/webmehr.com\/blog\/p_1614\/#%D8%A7%D9%81%D8%B2%D8%A7%DB%8C%D8%B4_%D9%82%D8%A7%D8%A8%D9%84_%D8%AA%D9%88%D8%AC%D9%87_%D8%AF%D8%B1_Bounce_Rate\" >\u0627\u0641\u0632\u0627\u06cc\u0634 \u0642\u0627\u0628\u0644 \u062a\u0648\u062c\u0647 \u062f\u0631 Bounce Rate<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/webmehr.com\/blog\/p_1614\/#%DA%A9%D8%A7%D9%87%D8%B4_%D9%86%D8%B1%D8%AE_%DA%A9%D9%84%DB%8C%DA%A9_%D8%B1%D9%88%DB%8C_%D9%86%D8%AA%D8%A7%DB%8C%D8%AC_%D8%AC%D8%B3%D8%AA%D8%AC%D9%88\" >\u06a9\u0627\u0647\u0634 \u0646\u0631\u062e \u06a9\u0644\u06cc\u06a9 \u0631\u0648\u06cc \u0646\u062a\u0627\u06cc\u062c \u062c\u0633\u062a\u062c\u0648<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/webmehr.com\/blog\/p_1614\/#%D8%A7%D9%81%D8%B2%D8%A7%DB%8C%D8%B4_%D9%86%D8%B1%D8%AE_%D8%AE%D8%B1%D9%88%D8%AC_%D8%A7%D8%B2_%D8%B3%D8%A7%DB%8C%D8%AA\" >\u0627\u0641\u0632\u0627\u06cc\u0634 \u0646\u0631\u062e \u062e\u0631\u0648\u062c \u0627\u0632 \u0633\u0627\u06cc\u062a<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-9\" href=\"https:\/\/webmehr.com\/blog\/p_1614\/#%D8%A7%D9%81%D8%B2%D8%A7%DB%8C%D8%B4_%D8%B3%D8%AE%D8%AA%DB%8C_%DA%A9%D9%84%D9%85%D8%A7%D8%AA_%DA%A9%D9%84%DB%8C%D8%AF%DB%8C\" >\u0627\u0641\u0632\u0627\u06cc\u0634 \u0633\u062e\u062a\u06cc \u06a9\u0644\u0645\u0627\u062a \u06a9\u0644\u06cc\u062f\u06cc<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-10\" href=\"https:\/\/webmehr.com\/blog\/p_1614\/#%D8%A7%D9%81%D8%B2%D8%A7%DB%8C%D8%B4_%DA%AF%D8%B2%D8%A7%D8%B1%D8%B4%D8%A7%D8%AA_%D8%A7%D8%B3%D9%BE%D9%85\" >\u0627\u0641\u0632\u0627\u06cc\u0634 \u06af\u0632\u0627\u0631\u0634\u0627\u062a \u0627\u0633\u067e\u0645<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-11\" href=\"https:\/\/webmehr.com\/blog\/p_1614\/#%D8%B1%D8%A7%D9%87%E2%80%8C%D9%87%D8%A7%DB%8C%DB%8C_%D8%A8%D8%B1%D8%A7%DB%8C_%D8%AC%D9%84%D9%88%DA%AF%DB%8C%D8%B1%DB%8C_%D8%A7%D8%B2_%D8%AC%D8%B1%DB%8C%D9%85%D9%87_%D9%BE%D9%86%DA%AF%D9%88%D8%A6%D9%86\" >\u0631\u0627\u0647\u200c\u0647\u0627\u06cc\u06cc \u0628\u0631\u0627\u06cc \u062c\u0644\u0648\u06af\u06cc\u0631\u06cc \u0627\u0632 \u062c\u0631\u06cc\u0645\u0647 \u067e\u0646\u06af\u0648\u0626\u0646<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-12\" href=\"https:\/\/webmehr.com\/blog\/p_1614\/#%D8%AC%D9%85%D8%B9%D8%A8%D9%86%D8%AF%DB%8C\" >\u062c\u0645\u0639\u0628\u0646\u062f\u06cc<\/a><\/li><\/ul><\/nav><\/div>\n\n\n<div class=\"kk-star-ratings kksr-auto kksr-align-center kksr-valign-top\"\n    data-payload='{&quot;align&quot;:&quot;center&quot;,&quot;id&quot;:&quot;1614&quot;,&quot;slug&quot;:&quot;default&quot;,&quot;valign&quot;:&quot;top&quot;,&quot;ignore&quot;:&quot;&quot;,&quot;reference&quot;:&quot;auto&quot;,&quot;class&quot;:&quot;&quot;,&quot;count&quot;:&quot;0&quot;,&quot;legendonly&quot;:&quot;&quot;,&quot;readonly&quot;:&quot;&quot;,&quot;score&quot;:&quot;0&quot;,&quot;starsonly&quot;:&quot;&quot;,&quot;best&quot;:&quot;5&quot;,&quot;gap&quot;:&quot;5&quot;,&quot;greet&quot;:&quot;\u0628\u0647 \u0627\u06cc\u0646 \u0645\u0637\u0644\u0628 \u0627\u0645\u062a\u06cc\u0627\u0632 \u062f\u0647\u06cc\u062f&quot;,&quot;legend&quot;:&quot;0\\\/5 - (0 \u0627\u0645\u062a\u06cc\u0627\u0632)&quot;,&quot;size&quot;:&quot;24&quot;,&quot;title&quot;:&quot;\u0627\u0644\u06af\u0648\u0631\u06cc\u062a\u0645 \u067e\u0646\u06af\u0648\u0626\u0646: \u0645\u0628\u0627\u0631\u0632\u0647 \u0628\u0627 \u0644\u06cc\u0646\u06a9\u200c\u0647\u0627\u06cc \u0627\u0633\u067e\u0645 \u0648 \u0627\u0631\u062a\u0642\u0627\u06cc \u0631\u062a\u0628\u0647\u200c\u0628\u0646\u062f\u06cc \u0637\u0628\u06cc\u0639\u06cc \u062c\u0633\u062a\u062c\u0648&quot;,&quot;width&quot;:&quot;0&quot;,&quot;_legend&quot;:&quot;{score}\\\/{best} - ({count} {votes})&quot;,&quot;font_factor&quot;:&quot;1.25&quot;}'>\n            \n<div class=\"kksr-stars\">\n    \n<div class=\"kksr-stars-inactive\">\n            <div class=\"kksr-star\" data-star=\"1\" style=\"padding-left: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"2\" style=\"padding-left: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"3\" style=\"padding-left: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"4\" style=\"padding-left: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"5\" style=\"padding-left: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n    <\/div>\n    \n<div class=\"kksr-stars-active\" style=\"width: 0px;\">\n            <div class=\"kksr-star\" style=\"padding-left: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-left: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-left: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-left: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-left: 5px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 24px; height: 24px;\"><\/div>\n        <\/div>\n    <\/div>\n<\/div>\n                \n\n<div class=\"kksr-legend\" style=\"font-size: 19.2px;\">\n            <span class=\"kksr-muted\">\u0628\u0647 \u0627\u06cc\u0646 \u0645\u0637\u0644\u0628 \u0627\u0645\u062a\u06cc\u0627\u0632 \u062f\u0647\u06cc\u062f<\/span>\n    <\/div>\n    <\/div>\n<h2 style=\"text-align: justify\"><span class=\"ez-toc-section\" id=\"%D9%85%D9%82%D8%AF%D9%85%D9%87\"><\/span><span style=\"font-size: 14pt;color: #003366\">\u0645\u0642\u062f\u0645\u0647<\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p style=\"text-align: justify\">\n\u0627\u0644\u06af\u0631\u06cc\u062a\u0645 \u067e\u0646\u06af\u0648\u0626\u0646 \u06cc\u06a9\u06cc \u0627\u0632 \u0627\u0644\u06af\u0648\u0631\u06cc\u062a\u0645\u200c\u0647\u0627\u06cc \u0645\u0647\u0645 \u0645\u0648\u062a\u0648\u0631 \u062c\u0633\u062a\u062c\u0648\u06cc \u06af\u0648\u06af\u0644 \u0627\u0633\u062a \u06a9\u0647 \u062f\u0631 \u0633\u0627\u0644 2012 \u0645\u0639\u0631\u0641\u06cc \u0634\u062f. \u0627\u06cc\u0646 \u0627\u0644\u06af\u0648\u0631\u06cc\u062a\u0645 \u0628\u0647 \u0645\u0646\u0638\u0648\u0631 \u0645\u0642\u0627\u0628\u0644\u0647 \u0628\u0627 \u0633\u0627\u06cc\u062a\u200c\u0647\u0627\u06cc\u06cc \u06a9\u0647 \u0627\u0632 \u0631\u0648\u0634\u200c\u0647\u0627\u06cc \u063a\u06cc\u0631\u0637\u0628\u06cc\u0639\u06cc \u0628\u0631\u0627\u06cc \u0628\u0647\u0628\u0648\u062f \u0631\u062a\u0628\u0647\u200c\u0628\u0646\u062f\u06cc \u062e\u0648\u062f \u062f\u0631 \u0646\u062a\u0627\u06cc\u062c \u062c\u0633\u062a\u062c\u0648 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0645\u06cc\u200c\u06a9\u0646\u0646\u062f\u060c \u0637\u0631\u0627\u062d\u06cc \u0634\u062f\u0647 \u0627\u0633\u062a. \u067e\u0646\u06af\u0648\u0626\u0646 \u0628\u0647\u200c\u0637\u0648\u0631 \u062e\u0627\u0635 \u0628\u0647 \u0644\u06cc\u0646\u06a9\u200c\u0647\u0627\u06cc \u0627\u0633\u067e\u0645 \u062a\u0648\u062c\u0647 \u062f\u0627\u0631\u062f \u0648 \u0633\u0627\u06cc\u062a\u200c\u0647\u0627\u06cc\u06cc \u06a9\u0647 \u0631\u062a\u0628\u0647\u200c\u0628\u0646\u062f\u06cc \u0622\u0646\u0647\u0627 \u0628\u0627 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0632 \u0644\u06cc\u0646\u06a9\u200c\u0647\u0627\u06cc \u0627\u0633\u067e\u0645 \u062f\u0633\u062a\u06a9\u0627\u0631\u06cc \u0634\u062f\u0647 \u0627\u0633\u062a\u060c \u0645\u0645\u06a9\u0646 \u0627\u0633\u062a \u0627\u0632 \u0646\u062a\u0627\u06cc\u062c \u062c\u0633\u062a\u062c\u0648 \u062d\u0630\u0641 \u0634\u0648\u0646\u062f \u06cc\u0627 \u0631\u062a\u0628\u0647\u200c\u0628\u0646\u062f\u06cc \u0622\u0646\u0647\u0627 \u0628\u0647\u200c\u0637\u0648\u0631 \u0686\u0634\u0645\u06af\u06cc\u0631\u06cc \u06a9\u0627\u0647\u0634 \u06cc\u0627\u0628\u062f.<\/p>\n<h2 style=\"text-align: justify\"><span class=\"ez-toc-section\" id=\"%D9%86%D8%AD%D9%88%D9%87%E2%80%8C%DB%8C_%D8%B9%D9%85%D9%84%DA%A9%D8%B1%D8%AF_%D9%BE%D9%86%DA%AF%D9%88%D8%A6%D9%86\"><\/span><span style=\"font-size: 14pt;color: #003366\">\u0646\u062d\u0648\u0647\u200c\u06cc \u0639\u0645\u0644\u06a9\u0631\u062f \u067e\u0646\u06af\u0648\u0626\u0646<\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p style=\"text-align: justify\">\n\u067e\u0646\u06af\u0648\u0626\u0646 \u0627\u0632 \u06cc\u06a9 \u0627\u0644\u06af\u0648\u0631\u06cc\u062a\u0645 \u067e\u06cc\u0686\u06cc\u062f\u0647 \u0628\u0631\u0627\u06cc \u0634\u0646\u0627\u0633\u0627\u06cc\u06cc \u0648 \u0631\u062a\u0628\u0647\u200c\u0628\u0646\u062f\u06cc \u0644\u06cc\u0646\u06a9\u200c\u0647\u0627\u06cc \u0627\u0633\u067e\u0645 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0645\u06cc\u200c\u06a9\u0646\u062f. \u0627\u06cc\u0646 \u0627\u0644\u06af\u0648\u0631\u06cc\u062a\u0645 \u0628\u0647 \u0639\u0648\u0627\u0645\u0644 \u0645\u062e\u062a\u0644\u0641\u06cc \u06a9\u0647 \u062f\u0631 \u0627\u062f\u0627\u0645\u0647 \u0628\u0647 \u0622\u0646 \u0645\u06cc\u067e\u0631\u062f\u0627\u0632\u06cc\u0645 \u062a\u0648\u062c\u0647 \u0645\u06cc\u200c\u06a9\u0646\u062f.<br \/>\n\u0627\u06cc\u0646 \u0639\u0648\u0627\u0645\u0644 \u0639\u0628\u0627\u0631\u062a\u0646\u062f \u0627\u0632:<\/p>\n<h2 style=\"text-align: justify\"><span class=\"ez-toc-section\" id=\"%D8%B4%D9%86%D8%A7%D8%B3%D8%A7%DB%8C%DB%8C_%D9%88%D8%A8%E2%80%8C%D8%B3%D8%A7%DB%8C%D8%AA%E2%80%8C%D9%87%D8%A7%DB%8C_%D8%A8%D8%A7_%D9%85%D8%AD%D8%AA%D9%88%D8%A7%DB%8C_%D8%A7%D8%B3%D9%BE%D9%85\"><\/span><span style=\"font-size: 14pt;color: #003366\"><strong>\u0634\u0646\u0627\u0633\u0627\u06cc\u06cc \u0648\u0628\u200c\u0633\u0627\u06cc\u062a\u200c\u0647\u0627\u06cc \u0628\u0627 \u0645\u062d\u062a\u0648\u0627\u06cc \u0627\u0633\u067e\u0645<\/strong><\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p style=\"text-align: justify\">\u0627\u0644\u06af\u0648\u0631\u06cc\u062a\u0645 \u067e\u0646\u06af\u0648\u0626\u0646 \u0648\u0628\u200c\u0633\u0627\u06cc\u062a\u200c\u0647\u0627\u06cc \u0628\u0627 \u0645\u062d\u062a\u0648\u0627\u06cc \u0627\u0633\u067e\u0645 \u0631\u0627 \u0628\u0627 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0632 \u0686\u0646\u062f\u06cc\u0646 \u0639\u0627\u0645\u0644 \u0634\u0646\u0627\u0633\u0627\u06cc\u06cc \u0645\u06cc\u200c\u06a9\u0646\u062f\u060c \u0627\u0632 \u062c\u0645\u0644\u0647:<br \/>\n<strong>\u2022 \u0645\u062d\u062a\u0648\u0627\u06cc \u062a\u06a9\u0631\u0627\u0631\u06cc:<\/strong> \u0645\u062d\u062a\u0648\u0627\u06cc \u062a\u06a9\u0631\u0627\u0631\u06cc \u06cc\u06a9\u06cc \u0627\u0632 \u0646\u0634\u0627\u0646\u0647\u200c\u0647\u0627\u06cc \u0627\u0635\u0644\u06cc \u0627\u0633\u067e\u0645 \u0627\u0633\u062a. \u0627\u0644\u06af\u0648\u0631\u06cc\u062a\u0645 \u067e\u0646\u06af\u0648\u0626\u0646 \u0628\u0647 \u062f\u0646\u0628\u0627\u0644 \u0648\u0628\u200c\u0633\u0627\u06cc\u062a\u200c\u0647\u0627\u06cc\u06cc \u0627\u0633\u062a \u06a9\u0647 \u0645\u062d\u062a\u0648\u0627\u06cc \u062e\u0648\u062f \u0631\u0627 \u0627\u0632 \u0645\u0646\u0627\u0628\u0639 \u062f\u06cc\u06af\u0631 \u06a9\u067e\u06cc \u0645\u06cc\u200c\u06a9\u0646\u0646\u062f.<br \/>\n<strong>\u2022 \u0644\u06cc\u0646\u06a9\u200c\u0647\u0627\u06cc \u062e\u0627\u0631\u062c\u06cc \u0645\u0634\u06a9\u0648\u06a9:<\/strong> \u0644\u06cc\u0646\u06a9\u200c\u0647\u0627\u06cc \u062e\u0627\u0631\u062c\u06cc \u0645\u0634\u06a9\u0648\u06a9 \u06cc\u06a9\u06cc \u062f\u06cc\u06af\u0631 \u0627\u0632 \u0646\u0634\u0627\u0646\u0647\u200c\u0647\u0627\u06cc \u0627\u0635\u0644\u06cc \u0627\u0633\u067e\u0645 \u0627\u0633\u062a. \u0627\u0644\u06af\u0648\u0631\u06cc\u062a\u0645 \u067e\u0646\u06af\u0648\u0626\u0646 \u0628\u0647 \u062f\u0646\u0628\u0627\u0644 \u0648\u0628\u200c\u0633\u0627\u06cc\u062a\u200c\u0647\u0627\u06cc\u06cc \u0627\u0633\u062a \u06a9\u0647 \u0627\u0632 \u0644\u06cc\u0646\u06a9\u200c\u0647\u0627\u06cc \u062e\u0627\u0631\u062c\u06cc \u0645\u0634\u06a9\u0648\u06a9 \u0628\u0631\u0627\u06cc \u0627\u0641\u0632\u0627\u06cc\u0634 \u0631\u062a\u0628\u0647 \u062e\u0648\u062f \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0645\u06cc\u200c\u06a9\u0646\u0646\u062f.<br \/>\n<strong>\u2022 \u0627\u0639\u062a\u0628\u0627\u0631 \u0648\u0628\u200c\u0633\u0627\u06cc\u062a:<\/strong> \u0627\u0644\u06af\u0648\u0631\u06cc\u062a\u0645 \u067e\u0646\u06af\u0648\u0626\u0646 \u0628\u0647 \u0627\u0639\u062a\u0628\u0627\u0631 \u0648\u0628\u200c\u0633\u0627\u06cc\u062a \u0646\u06cc\u0632 \u062a\u0648\u062c\u0647 \u0645\u06cc\u200c\u06a9\u0646\u062f. \u0648\u0628\u200c\u0633\u0627\u06cc\u062a\u200c\u0647\u0627\u06cc\u06cc \u06a9\u0647 \u0627\u0639\u062a\u0628\u0627\u0631 \u067e\u0627\u06cc\u06cc\u0646\u06cc \u062f\u0627\u0631\u0646\u062f\u060c \u0628\u06cc\u0634\u062a\u0631 \u062f\u0631 \u0645\u0639\u0631\u0636 \u0634\u0646\u0627\u0633\u0627\u06cc\u06cc \u0628\u0647 \u0639\u0646\u0648\u0627\u0646 \u0648\u0628\u200c\u0633\u0627\u06cc\u062a\u200c\u0647\u0627\u06cc \u0627\u0633\u067e\u0645 \u0647\u0633\u062a\u0646\u062f.<\/p>\n<p style=\"text-align: justify\">\u0627\u0644\u06af\u0648\u0631\u06cc\u062a\u0645 \u067e\u0646\u06af\u0648\u0626\u0646 \u06cc\u06a9\u06cc \u0627\u0632 \u0627\u0628\u0632\u0627\u0631\u0647\u0627\u06cc \u0645\u0647\u0645 \u06af\u0648\u06af\u0644 \u0628\u0631\u0627\u06cc \u0645\u0642\u0627\u0628\u0644\u0647 \u0628\u0627 \u0627\u0633\u067e\u0645 \u0627\u0633\u062a. \u0627\u06af\u0631 \u0648\u0628\u200c\u0633\u0627\u06cc\u062a \u0634\u0645\u0627 \u0627\u0632 \u0645\u062d\u062a\u0648\u0627\u06cc \u0627\u0633\u067e\u0645 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0645\u06cc\u200c\u06a9\u0646\u062f\u060c \u0645\u0645\u06a9\u0646 \u0627\u0633\u062a \u0631\u062a\u0628\u0647 \u0622\u0646 \u062f\u0631 \u0646\u062a\u0627\u06cc\u062c \u062c\u0633\u062a\u062c\u0648 \u06a9\u0627\u0647\u0634 \u06cc\u0627\u0628\u062f. \u0628\u0631\u0627\u06cc \u062c\u0644\u0648\u06af\u06cc\u0631\u06cc \u0627\u0632 \u0627\u06cc\u0646 \u0645\u0634\u06a9\u0644\u060c \u0628\u0627\u06cc\u062f \u0627\u0632 \u0646\u06a9\u0627\u062a\u06cc \u06a9\u0647 \u062f\u0631 \u0627\u06cc\u0646 \u0645\u0642\u0627\u0644\u0647 \u0630\u06a9\u0631 \u0634\u062f \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u06a9\u0646\u06cc\u062f.<\/p>\n<h2 style=\"text-align: justify\"><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter size-medium wp-image-1615\" src=\"https:\/\/webmehr.com\/blog\/wp-content\/uploads\/2024\/01\/google-penguin-1-300x239.jpg\" alt=\"\" width=\"300\" height=\"239\" srcset=\"https:\/\/webmehr.com\/blog\/wp-content\/uploads\/2024\/01\/google-penguin-1-300x239.jpg 300w, https:\/\/webmehr.com\/blog\/wp-content\/uploads\/2024\/01\/google-penguin-1.jpg 600w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><br \/>\n<span style=\"font-size: 14pt;color: #003366\"><strong>\u0639\u0644\u0627\u0626\u0645 \u0642\u0631\u0645\u0632 \u0628\u0631\u0627\u06cc \u0633\u0627\u06cc\u062a \u0634\u0645\u0627: \u0647\u0634\u062f\u0627\u0631\u0647\u0627 \u0628\u0631\u0627\u06cc \u062c\u0644\u0648\u06af\u06cc\u0631\u06cc \u0627\u0632 \u062c\u0631\u06cc\u0645\u0647 Penguin \u06af\u0648\u06af\u0644<\/strong><\/span><\/h2>\n<p style=\"text-align: justify\">\u2022 \u062a\u063a\u06cc\u06cc\u0631 \u0646\u0627\u06af\u0647\u0627\u0646\u06cc \u062f\u0631 \u0631\u062a\u0628\u0647 \u0628\u0646\u062f\u06cc \u0633\u0627\u06cc\u062a \u0634\u0645\u0627<br \/>\n\u2022 \u0627\u0641\u0632\u0627\u06cc\u0634 \u0642\u0627\u0628\u0644 \u062a\u0648\u062c\u0647 \u062f\u0631 Bounce Rate<br \/>\n\u2022 \u06a9\u0627\u0647\u0634 \u0646\u0631\u062e \u06a9\u0644\u06cc\u06a9 \u0631\u0648\u06cc \u0646\u062a\u0627\u06cc\u062c \u062c\u0633\u062a\u062c\u0648<br \/>\n\u2022 \u0627\u0641\u0632\u0627\u06cc\u0634 \u0646\u0631\u062e \u062e\u0631\u0648\u062c \u0627\u0632 \u0633\u0627\u06cc\u062a<br \/>\n\u2022 \u0627\u0641\u0632\u0627\u06cc\u0634 \u0633\u062e\u062a\u06cc \u06a9\u0644\u0645\u0627\u062a \u06a9\u0644\u06cc\u062f\u06cc<br \/>\n\u2022 \u0627\u0641\u0632\u0627\u06cc\u0634 \u06af\u0632\u0627\u0631\u0634\u0627\u062a \u0627\u0633\u067e\u0645<\/p>\n<h2 style=\"text-align: justify\"><span class=\"ez-toc-section\" id=\"%D8%AA%D8%BA%DB%8C%DB%8C%D8%B1_%D9%86%D8%A7%DA%AF%D9%87%D8%A7%D9%86%DB%8C_%D8%AF%D8%B1_%D8%B1%D8%AA%D8%A8%D9%87_%D8%A8%D9%86%D8%AF%DB%8C_%D8%B3%D8%A7%DB%8C%D8%AA_%D8%B4%D9%85%D8%A7\"><\/span><span style=\"font-size: 14pt;color: #003366\">\u062a\u063a\u06cc\u06cc\u0631 \u0646\u0627\u06af\u0647\u0627\u0646\u06cc \u062f\u0631 \u0631\u062a\u0628\u0647 \u0628\u0646\u062f\u06cc \u0633\u0627\u06cc\u062a \u0634\u0645\u0627<\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p style=\"text-align: justify\">\n\u06cc\u06a9\u06cc \u0627\u0632 \u0627\u0648\u0644\u06cc\u0646 \u0646\u0634\u0627\u0646\u0647\u200c\u0647\u0627\u06cc \u0627\u06cc\u0646\u06a9\u0647 \u0645\u0645\u06a9\u0646 \u0627\u0633\u062a \u0633\u0627\u06cc\u062a \u0634\u0645\u0627 \u062a\u0648\u0633\u0637 \u067e\u0646\u06af\u0648\u0626\u0646 \u062c\u0631\u06cc\u0645\u0647 \u0634\u062f\u0647 \u0628\u0627\u0634\u062f\u060c \u062a\u063a\u06cc\u06cc\u0631 \u0646\u0627\u06af\u0647\u0627\u0646\u06cc \u062f\u0631 \u0631\u062a\u0628\u0647 \u0628\u0646\u062f\u06cc \u0633\u0627\u06cc\u062a \u0634\u0645\u0627 \u062f\u0631 \u0646\u062a\u0627\u06cc\u062c \u062c\u0633\u062a\u062c\u0648 \u0627\u0633\u062a. \u0627\u06af\u0631 \u0633\u0627\u06cc\u062a \u0634\u0645\u0627 \u0628\u0647 \u0637\u0648\u0631 \u0646\u0627\u06af\u0647\u0627\u0646\u06cc \u0634\u0631\u0648\u0639 \u0628\u0647 \u0627\u0641\u062a \u0631\u062a\u0628\u0647 \u06a9\u0646\u062f\u060c \u0645\u0645\u06a9\u0646 \u0627\u0633\u062a \u0628\u0647 \u0627\u06cc\u0646 \u062f\u0644\u06cc\u0644 \u0628\u0627\u0634\u062f \u06a9\u0647 \u06af\u0648\u06af\u0644 \u0645\u062a\u0648\u062c\u0647 \u0634\u062f\u0647 \u0627\u0633\u062a \u06a9\u0647 \u0633\u0627\u06cc\u062a \u0634\u0645\u0627 \u0627\u0632 \u062a\u06a9\u0646\u06cc\u06a9\u200c\u0647\u0627\u06cc \u0633\u0626\u0648\u06cc \u06a9\u0644\u0627\u0647 \u0633\u06cc\u0627\u0647 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0645\u06cc\u200c\u06a9\u0646\u062f.<\/p>\n<h2 style=\"text-align: justify\"><img decoding=\"async\" class=\"aligncenter size-medium wp-image-1616\" src=\"https:\/\/webmehr.com\/blog\/wp-content\/uploads\/2024\/01\/google-panguin-algorithm-large-Cover-belovedmarketing-300x140.jpg\" alt=\"\" width=\"300\" height=\"140\" srcset=\"https:\/\/webmehr.com\/blog\/wp-content\/uploads\/2024\/01\/google-panguin-algorithm-large-Cover-belovedmarketing-300x140.jpg 300w, https:\/\/webmehr.com\/blog\/wp-content\/uploads\/2024\/01\/google-panguin-algorithm-large-Cover-belovedmarketing-1024x478.jpg 1024w, https:\/\/webmehr.com\/blog\/wp-content\/uploads\/2024\/01\/google-panguin-algorithm-large-Cover-belovedmarketing-768x358.jpg 768w, https:\/\/webmehr.com\/blog\/wp-content\/uploads\/2024\/01\/google-panguin-algorithm-large-Cover-belovedmarketing.jpg 1200w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><br \/>\n<span style=\"color: #003366;font-size: 14pt\">\u0627\u0641\u0632\u0627\u06cc\u0634 \u0642\u0627\u0628\u0644 \u062a\u0648\u062c\u0647 \u062f\u0631 Bounce Rate<\/span><\/h2>\n<p style=\"text-align: justify\">\n<strong>Bounce Rate<\/strong> \u0646\u0631\u062e \u0628\u0627\u0632\u06af\u0634\u062a \u0628\u0627\u0632\u062f\u06cc\u062f\u06a9\u0646\u0646\u062f\u06af\u0627\u0646 \u0628\u0647 \u0635\u0641\u062d\u0647 \u0627\u0635\u0644\u06cc \u0633\u0627\u06cc\u062a \u0627\u0633\u062a. \u0627\u06af\u0631 <strong>bounce rate<\/strong> \u0633\u0627\u06cc\u062a \u0634\u0645\u0627 \u0628\u0647 \u0637\u0648\u0631 \u0642\u0627\u0628\u0644 \u062a\u0648\u062c\u0647\u06cc \u0627\u0641\u0632\u0627\u06cc\u0634 \u06cc\u0627\u0628\u062f\u060c \u0645\u0645\u06a9\u0646 \u0627\u0633\u062a \u0628\u0647 \u0627\u06cc\u0646 \u062f\u0644\u06cc\u0644 \u0628\u0627\u0634\u062f \u06a9\u0647 \u0628\u0627\u0632\u062f\u06cc\u062f\u06a9\u0646\u0646\u062f\u06af\u0627\u0646 \u0646\u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u0646\u062f \u0645\u062d\u062a\u0648\u0627\u06cc \u0645\u0631\u062a\u0628\u0637 \u0628\u0627 \u0622\u0646\u0686\u0647 \u062c\u0633\u062a\u062c\u0648 \u06a9\u0631\u062f\u0647\u200c\u0627\u0646\u062f \u0631\u0627 \u062f\u0631 \u0633\u0627\u06cc\u062a \u0634\u0645\u0627 \u067e\u06cc\u062f\u0627 \u06a9\u0646\u0646\u062f. \u0627\u06cc\u0646 \u0627\u0645\u0631 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f \u0646\u0634\u0627\u0646 \u062f\u0647\u062f \u06a9\u0647 \u0633\u0627\u06cc\u062a \u0634\u0645\u0627 \u0627\u0632 \u062a\u06a9\u0646\u06cc\u06a9\u200c\u0647\u0627\u06cc \u0633\u0626\u0648\u06cc \u06a9\u0644\u0627\u0647 \u0633\u06cc\u0627\u0647 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0645\u06cc\u200c\u06a9\u0646\u062f \u06a9\u0647 \u0628\u0627\u0639\u062b \u0645\u06cc\u200c\u0634\u0648\u062f \u0633\u0627\u06cc\u062a \u0634\u0645\u0627 \u062f\u0631 \u0646\u062a\u0627\u06cc\u062c \u062c\u0633\u062a\u062c\u0648 \u0631\u062a\u0628\u0647 \u0628\u0627\u0644\u0627\u062a\u0631\u06cc \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u062f\u060c \u0627\u0645\u0627 \u062a\u062c\u0631\u0628\u0647 \u06a9\u0627\u0631\u0628\u0631\u06cc \u062e\u0648\u0628\u06cc \u0631\u0627 \u0627\u0631\u0627\u0626\u0647 \u0646\u0645\u06cc\u200c\u062f\u0647\u062f.<\/p>\n<h2 style=\"text-align: justify\"><span class=\"ez-toc-section\" id=\"%DA%A9%D8%A7%D9%87%D8%B4_%D9%86%D8%B1%D8%AE_%DA%A9%D9%84%DB%8C%DA%A9_%D8%B1%D9%88%DB%8C_%D9%86%D8%AA%D8%A7%DB%8C%D8%AC_%D8%AC%D8%B3%D8%AA%D8%AC%D9%88\"><\/span><span style=\"font-size: 14pt;color: #003366\">\u06a9\u0627\u0647\u0634 \u0646\u0631\u062e \u06a9\u0644\u06cc\u06a9 \u0631\u0648\u06cc \u0646\u062a\u0627\u06cc\u062c \u062c\u0633\u062a\u062c\u0648<\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p style=\"text-align: justify\">\n<strong>CTR (Click-Through Rate)<\/strong> \u0646\u0631\u062e \u06a9\u0644\u06cc\u06a9 \u0631\u0648\u06cc \u0646\u062a\u0627\u06cc\u062c \u062c\u0633\u062a\u062c\u0648 \u0627\u0633\u062a. \u0627\u06af\u0631 <strong>CTR<\/strong> \u0633\u0627\u06cc\u062a \u0634\u0645\u0627 \u0628\u0647 \u0637\u0648\u0631 \u0642\u0627\u0628\u0644 \u062a\u0648\u062c\u0647\u06cc \u06a9\u0627\u0647\u0634 \u06cc\u0627\u0628\u062f\u060c \u0645\u0645\u06a9\u0646 \u0627\u0633\u062a \u0628\u0647 \u0627\u06cc\u0646 \u062f\u0644\u06cc\u0644 \u0628\u0627\u0634\u062f \u06a9\u0647 \u0628\u0627\u0632\u062f\u06cc\u062f\u06a9\u0646\u0646\u062f\u06af\u0627\u0646 \u0627\u0632 \u0646\u062a\u0627\u06cc\u062c \u062c\u0633\u062a\u062c\u0648 \u0628\u0631\u0627\u06cc \u06a9\u0644\u06cc\u06a9 \u0628\u0631 \u0631\u0648\u06cc \u0633\u0627\u06cc\u062a \u0634\u0645\u0627 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0646\u0645\u06cc\u200c\u06a9\u0646\u0646\u062f. \u0627\u06cc\u0646 \u0627\u0645\u0631 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f \u0646\u0634\u0627\u0646 \u062f\u0647\u062f \u06a9\u0647 \u0633\u0627\u06cc\u062a \u0634\u0645\u0627 \u0627\u0632 \u062a\u06a9\u0646\u06cc\u06a9\u200c\u0647\u0627\u06cc \u0633\u0626\u0648\u06cc \u06a9\u0644\u0627\u0647 \u0633\u06cc\u0627\u0647 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0645\u06cc\u200c\u06a9\u0646\u062f \u06a9\u0647 \u0628\u0627\u0639\u062b \u0645\u06cc\u200c\u0634\u0648\u062f \u0633\u0627\u06cc\u062a \u0634\u0645\u0627 \u0628\u0631\u0627\u06cc \u0628\u0627\u0632\u062f\u06cc\u062f\u06a9\u0646\u0646\u062f\u06af\u0627\u0646 \u06a9\u0645\u062a\u0631 \u0645\u0631\u062a\u0628\u0637 \u0628\u0627\u0634\u062f.<\/p>\n<h2 style=\"text-align: justify\"><span class=\"ez-toc-section\" id=\"%D8%A7%D9%81%D8%B2%D8%A7%DB%8C%D8%B4_%D9%86%D8%B1%D8%AE_%D8%AE%D8%B1%D9%88%D8%AC_%D8%A7%D8%B2_%D8%B3%D8%A7%DB%8C%D8%AA\"><\/span><span style=\"font-size: 14pt;color: #003366\">\u0627\u0641\u0632\u0627\u06cc\u0634 \u0646\u0631\u062e \u062e\u0631\u0648\u062c \u0627\u0632 \u0633\u0627\u06cc\u062a<\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p style=\"text-align: justify\">\nExit Rate \u0646\u0631\u062e \u062e\u0631\u0648\u062c \u0627\u0632 \u0633\u0627\u06cc\u062a \u0627\u0633\u062a. \u0627\u06af\u0631 exit rate \u0633\u0627\u06cc\u062a \u0634\u0645\u0627 \u0628\u0647 \u0637\u0648\u0631 \u0642\u0627\u0628\u0644 \u062a\u0648\u062c\u0647\u06cc \u0627\u0641\u0632\u0627\u06cc\u0634 \u06cc\u0627\u0628\u062f\u060c \u0645\u0645\u06a9\u0646 \u0627\u0633\u062a \u0628\u0647 \u0627\u06cc\u0646 \u062f\u0644\u06cc\u0644 \u0628\u0627\u0634\u062f \u06a9\u0647 \u0628\u0627\u0632\u062f\u06cc\u062f\u06a9\u0646\u0646\u062f\u06af\u0627\u0646 \u067e\u0633 \u0627\u0632 \u0648\u0631\u0648\u062f \u0628\u0647 \u0633\u0627\u06cc\u062a \u0634\u0645\u0627\u060c \u062e\u06cc\u0644\u06cc \u0633\u0631\u06cc\u0639 \u0622\u0646 \u0631\u0627 \u062a\u0631\u06a9 \u0645\u06cc\u200c\u06a9\u0646\u0646\u062f. \u0627\u06cc\u0646 \u0627\u0645\u0631 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f \u0646\u0634\u0627\u0646 \u062f\u0647\u062f \u06a9\u0647 \u0633\u0627\u06cc\u062a \u0634\u0645\u0627 \u0627\u0632 \u062a\u06a9\u0646\u06cc\u06a9\u200c\u0647\u0627\u06cc \u0633\u0626\u0648\u06cc \u06a9\u0644\u0627\u0647 \u0633\u06cc\u0627\u0647 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0645\u06cc\u200c\u06a9\u0646\u062f \u06a9\u0647 \u0628\u0627\u0639\u062b \u0645\u06cc\u200c\u0634\u0648\u062f \u0633\u0627\u06cc\u062a \u0634\u0645\u0627 \u0628\u0631\u0627\u06cc \u0628\u0627\u0632\u062f\u06cc\u062f\u06a9\u0646\u0646\u062f\u06af\u0627\u0646 \u062c\u0630\u0627\u0628 \u0646\u0628\u0627\u0634\u062f.<\/p>\n<h2 style=\"text-align: justify\"><img decoding=\"async\" class=\"aligncenter size-medium wp-image-1617\" src=\"https:\/\/webmehr.com\/blog\/wp-content\/uploads\/2024\/01\/google-penguin-update-300x139.jpg\" alt=\"\" width=\"300\" height=\"139\" srcset=\"https:\/\/webmehr.com\/blog\/wp-content\/uploads\/2024\/01\/google-penguin-update-300x139.jpg 300w, https:\/\/webmehr.com\/blog\/wp-content\/uploads\/2024\/01\/google-penguin-update-768x355.jpg 768w, https:\/\/webmehr.com\/blog\/wp-content\/uploads\/2024\/01\/google-penguin-update.jpg 893w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/h2>\n<h2 style=\"text-align: justify\"><span class=\"ez-toc-section\" id=\"%D8%A7%D9%81%D8%B2%D8%A7%DB%8C%D8%B4_%D8%B3%D8%AE%D8%AA%DB%8C_%DA%A9%D9%84%D9%85%D8%A7%D8%AA_%DA%A9%D9%84%DB%8C%D8%AF%DB%8C\"><\/span><span style=\"font-size: 14pt;color: #003366\">\u0627\u0641\u0632\u0627\u06cc\u0634 \u0633\u062e\u062a\u06cc \u06a9\u0644\u0645\u0627\u062a \u06a9\u0644\u06cc\u062f\u06cc<\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p style=\"text-align: justify\">\n\u0633\u062e\u062a\u06cc \u06a9\u0644\u0645\u0647 \u06a9\u0644\u06cc\u062f\u06cc \u06cc\u06a9 \u0634\u0627\u062e\u0635 \u0627\u0633\u062a \u06a9\u0647 \u0646\u0634\u0627\u0646 \u0645\u06cc\u200c\u062f\u0647\u062f \u0686\u0642\u062f\u0631 \u0631\u0642\u0627\u0628\u062a \u0633\u062e\u062a\u06cc \u0628\u0631\u0627\u06cc \u0631\u062a\u0628\u0647 \u0628\u0646\u062f\u06cc \u0628\u0631\u0627\u06cc \u06cc\u06a9 \u06a9\u0644\u0645\u0647 \u06a9\u0644\u06cc\u062f\u06cc \u062e\u0627\u0635 \u0648\u062c\u0648\u062f \u062f\u0627\u0631\u062f. \u0627\u06af\u0631 \u0633\u062e\u062a\u06cc \u06a9\u0644\u0645\u0627\u062a \u06a9\u0644\u06cc\u062f\u06cc \u06a9\u0647 \u0628\u0631\u0627\u06cc \u0622\u0646\u0647\u0627 \u0631\u062a\u0628\u0647 \u0628\u0646\u062f\u06cc \u0645\u06cc\u200c\u06a9\u0646\u06cc\u062f \u0628\u0647 \u0637\u0648\u0631 \u0642\u0627\u0628\u0644 \u062a\u0648\u062c\u0647\u06cc \u0627\u0641\u0632\u0627\u06cc\u0634 \u06cc\u0627\u0628\u062f\u060c \u0645\u0645\u06a9\u0646 \u0627\u0633\u062a \u0628\u0647 \u0627\u06cc\u0646 \u062f\u0644\u06cc\u0644 \u0628\u0627\u0634\u062f \u06a9\u0647 \u06af\u0648\u06af\u0644 \u0645\u062a\u0648\u062c\u0647 \u0634\u062f\u0647 \u0627\u0633\u062a \u06a9\u0647 \u0633\u0627\u06cc\u062a \u0634\u0645\u0627 \u0627\u0632 \u062a\u06a9\u0646\u06cc\u06a9\u200c\u0647\u0627\u06cc \u0633\u0626\u0648\u06cc \u06a9\u0644\u0627\u0647 \u0633\u06cc\u0627\u0647 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0645\u06cc\u200c\u06a9\u0646\u062f.<\/p>\n<h2 style=\"text-align: justify\"><span class=\"ez-toc-section\" id=\"%D8%A7%D9%81%D8%B2%D8%A7%DB%8C%D8%B4_%DA%AF%D8%B2%D8%A7%D8%B1%D8%B4%D8%A7%D8%AA_%D8%A7%D8%B3%D9%BE%D9%85\"><\/span><span style=\"font-size: 14pt;color: #003366\">\u0627\u0641\u0632\u0627\u06cc\u0634 \u06af\u0632\u0627\u0631\u0634\u0627\u062a \u0627\u0633\u067e\u0645<\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p style=\"text-align: justify\">\n\u0627\u06af\u0631 \u0628\u0627\u0632\u062f\u06cc\u062f\u06a9\u0646\u0646\u062f\u06af\u0627\u0646 \u0633\u0627\u06cc\u062a \u0634\u0645\u0627 \u0634\u0631\u0648\u0639 \u0628\u0647 \u06af\u0632\u0627\u0631\u0634 \u0633\u0627\u06cc\u062a \u0634\u0645\u0627 \u0628\u0647 \u0639\u0646\u0648\u0627\u0646 \u0627\u0633\u067e\u0645 \u06a9\u0646\u0646\u062f\u060c \u0627\u06cc\u0646 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f \u0646\u0634\u0627\u0646\u0647 \u062f\u06cc\u06af\u0631\u06cc \u0628\u0627\u0634\u062f \u06a9\u0647 \u0633\u0627\u06cc\u062a \u0634\u0645\u0627 \u0627\u0632 \u062a\u06a9\u0646\u06cc\u06a9\u200c\u0647\u0627\u06cc \u0633\u0626\u0648\u06cc \u06a9\u0644\u0627\u0647 \u0633\u06cc\u0627\u0647 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0645\u06cc\u200c\u06a9\u0646\u062f. \u0627\u06cc\u0646 \u06af\u0632\u0627\u0631\u0634\u0627\u062a \u0627\u0633\u067e\u0645 \u0645\u0645\u06a9\u0646 \u0627\u0633\u062a \u0628\u0627\u0639\u062b \u0634\u0648\u062f \u06a9\u0647 \u06af\u0648\u06af\u0644 \u0633\u0627\u06cc\u062a \u0634\u0645\u0627 \u0631\u0627 \u0628\u0631\u0631\u0633\u06cc \u06a9\u0646\u062f \u0648 \u0645\u0645\u06a9\u0646 \u0627\u0633\u062a \u0645\u0646\u062c\u0631 \u0628\u0647 \u062c\u0631\u06cc\u0645\u0647 \u0634\u062f\u0646 \u0633\u0627\u06cc\u062a \u0634\u0645\u0627 \u0634\u0648\u062f.<br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-1618\" src=\"https:\/\/webmehr.com\/blog\/wp-content\/uploads\/2024\/01\/penguin-algorithm-google-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/webmehr.com\/blog\/wp-content\/uploads\/2024\/01\/penguin-algorithm-google-300x200.jpg 300w, https:\/\/webmehr.com\/blog\/wp-content\/uploads\/2024\/01\/penguin-algorithm-google-768x512.jpg 768w, https:\/\/webmehr.com\/blog\/wp-content\/uploads\/2024\/01\/penguin-algorithm-google.jpg 1000w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n<h2 style=\"text-align: justify\"><span class=\"ez-toc-section\" id=\"%D8%B1%D8%A7%D9%87%E2%80%8C%D9%87%D8%A7%DB%8C%DB%8C_%D8%A8%D8%B1%D8%A7%DB%8C_%D8%AC%D9%84%D9%88%DA%AF%DB%8C%D8%B1%DB%8C_%D8%A7%D8%B2_%D8%AC%D8%B1%DB%8C%D9%85%D9%87_%D9%BE%D9%86%DA%AF%D9%88%D8%A6%D9%86\"><\/span><span style=\"font-size: 14pt;color: #003366\">\u0631\u0627\u0647\u200c\u0647\u0627\u06cc\u06cc \u0628\u0631\u0627\u06cc \u062c\u0644\u0648\u06af\u06cc\u0631\u06cc \u0627\u0632 \u062c\u0631\u06cc\u0645\u0647 \u067e\u0646\u06af\u0648\u0626\u0646<\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p style=\"text-align: justify\">\n\u0627\u06af\u0631 \u0646\u06af\u0631\u0627\u0646 \u0647\u0633\u062a\u06cc\u062f \u06a9\u0647 \u0633\u0627\u06cc\u062a \u0634\u0645\u0627 \u0645\u0645\u06a9\u0646 \u0627\u0633\u062a \u062a\u0648\u0633\u0637 \u067e\u0646\u06af\u0648\u0626\u0646 \u062c\u0631\u06cc\u0645\u0647 \u0634\u0648\u062f\u060c \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u06cc\u062f \u0627\u0642\u062f\u0627\u0645\u0627\u062a \u0632\u06cc\u0631 \u0631\u0627 \u0627\u0646\u062c\u0627\u0645 \u062f\u0647\u06cc\u062f \u062a\u0627 \u062e\u0637\u0631 \u062c\u0631\u06cc\u0645\u0647 \u0634\u062f\u0646 \u0633\u0627\u06cc\u062a \u062e\u0648\u062f \u0631\u0627 \u06a9\u0627\u0647\u0634 \u062f\u0647\u06cc\u062f:<br \/>\n\u2022 \u0627\u0632 \u062a\u06a9\u0646\u06cc\u06a9\u200c\u0647\u0627\u06cc \u0633\u0626\u0648\u06cc \u06a9\u0644\u0627\u0647 \u0633\u06cc\u0627\u0647 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0646\u06a9\u0646\u06cc\u062f.<br \/>\n\u2022 \u0645\u062d\u062a\u0648\u0627\u06cc \u0628\u0627 \u06a9\u06cc\u0641\u06cc\u062a \u0628\u0627\u0644\u0627 \u0627\u06cc\u062c\u0627\u062f \u06a9\u0646\u06cc\u062f \u06a9\u0647 \u0628\u0631\u0627\u06cc \u0628\u0627\u0632\u062f\u06cc\u062f\u06a9\u0646\u0646\u062f\u06af\u0627\u0646 \u0645\u0641\u06cc\u062f \u0628\u0627\u0634\u062f.<br \/>\n\u2022 \u0627\u0632 \u0644\u06cc\u0646\u06a9\u200c\u0647\u0627\u06cc \u0637\u0628\u06cc\u0639\u06cc \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u06a9\u0646\u06cc\u062f \u0648 \u0627\u0632 \u062e\u0631\u06cc\u062f \u0644\u06cc\u0646\u06a9 \u062e\u0648\u062f\u062f\u0627\u0631\u06cc \u06a9\u0646\u06cc\u062f.<br \/>\n\u2022 \u0645\u0637\u0645\u0626\u0646 \u0634\u0648\u06cc\u062f \u06a9\u0647 \u0633\u0627\u06cc\u062a \u0634\u0645\u0627 \u0627\u0632 \u0644\u062d\u0627\u0638 \u0641\u0646\u06cc \u0635\u062d\u06cc\u062d \u0627\u0633\u062a.<br \/>\n\u2022 \u0633\u0627\u06cc\u062a \u062e\u0648\u062f \u0631\u0627 \u0628\u0647 \u0637\u0648\u0631 \u0645\u0646\u0638\u0645 \u0628\u0631\u0631\u0633\u06cc \u06a9\u0646\u06cc\u062f \u062a\u0627 \u0628\u0628\u06cc\u0646\u06cc\u062f \u0622\u06cc\u0627 \u0647\u0631 \u06af\u0648\u0646\u0647 \u0645\u0634\u06a9\u0644\u06cc \u0648\u062c\u0648\u062f \u062f\u0627\u0631\u062f.<\/p>\n<p style=\"text-align: justify\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-1619\" src=\"https:\/\/webmehr.com\/blog\/wp-content\/uploads\/2024\/01\/\u0627\u0644\u06af\u0648\u0631\u06cc\u062a\u0645-\u067e\u0646\u06af\u0648\u0626\u0646-\u06af\u0648\u06af\u0644-\u0686\u06cc\u0633\u062a-\u0648-\u0686\u0637\u0648\u0631-\u06a9\u0627\u0631-\u0645\u06cc\u06a9\u0646\u062f-\u0686\u0637\u0648\u0631-\u0627\u0632-\u067e\u0646\u0627\u0644\u062a\u06cc-\u067e\u0646\u06af\u0648\u06cc\u0646-\u062f\u0631-\u0627\u0645\u0627\u0646-\u0628\u0645\u0627\u0646\u06cc\u0645-300x188.jpg\" alt=\"\" width=\"300\" height=\"188\" srcset=\"https:\/\/webmehr.com\/blog\/wp-content\/uploads\/2024\/01\/\u0627\u0644\u06af\u0648\u0631\u06cc\u062a\u0645-\u067e\u0646\u06af\u0648\u0626\u0646-\u06af\u0648\u06af\u0644-\u0686\u06cc\u0633\u062a-\u0648-\u0686\u0637\u0648\u0631-\u06a9\u0627\u0631-\u0645\u06cc\u06a9\u0646\u062f-\u0686\u0637\u0648\u0631-\u0627\u0632-\u067e\u0646\u0627\u0644\u062a\u06cc-\u067e\u0646\u06af\u0648\u06cc\u0646-\u062f\u0631-\u0627\u0645\u0627\u0646-\u0628\u0645\u0627\u0646\u06cc\u0645-300x188.jpg 300w, https:\/\/webmehr.com\/blog\/wp-content\/uploads\/2024\/01\/\u0627\u0644\u06af\u0648\u0631\u06cc\u062a\u0645-\u067e\u0646\u06af\u0648\u0626\u0646-\u06af\u0648\u06af\u0644-\u0686\u06cc\u0633\u062a-\u0648-\u0686\u0637\u0648\u0631-\u06a9\u0627\u0631-\u0645\u06cc\u06a9\u0646\u062f-\u0686\u0637\u0648\u0631-\u0627\u0632-\u067e\u0646\u0627\u0644\u062a\u06cc-\u067e\u0646\u06af\u0648\u06cc\u0646-\u062f\u0631-\u0627\u0645\u0627\u0646-\u0628\u0645\u0627\u0646\u06cc\u0645-768x480.jpg 768w, https:\/\/webmehr.com\/blog\/wp-content\/uploads\/2024\/01\/\u0627\u0644\u06af\u0648\u0631\u06cc\u062a\u0645-\u067e\u0646\u06af\u0648\u0626\u0646-\u06af\u0648\u06af\u0644-\u0686\u06cc\u0633\u062a-\u0648-\u0686\u0637\u0648\u0631-\u06a9\u0627\u0631-\u0645\u06cc\u06a9\u0646\u062f-\u0686\u0637\u0648\u0631-\u0627\u0632-\u067e\u0646\u0627\u0644\u062a\u06cc-\u067e\u0646\u06af\u0648\u06cc\u0646-\u062f\u0631-\u0627\u0645\u0627\u0646-\u0628\u0645\u0627\u0646\u06cc\u0645.jpg 800w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n<h2 style=\"text-align: justify\"><\/h2>\n<p style=\"text-align: justify\">\n\u0627\u06af\u0631 \u0633\u0627\u06cc\u062a \u0634\u0645\u0627 \u062a\u0648\u0633\u0637 \u067e\u0646\u06af\u0648\u0626\u0646 \u062c\u0631\u06cc\u0645\u0647 \u0634\u062f\u060c \u0645\u0645\u06a9\u0646 \u0627\u0633\u062a \u0631\u062a\u0628\u0647 \u0628\u0646\u062f\u06cc \u0633\u0627\u06cc\u062a \u0634\u0645\u0627 \u062f\u0631 \u0646\u062a\u0627\u06cc\u062c \u062c\u0633\u062a\u062c\u0648 \u06a9\u0627\u0647\u0634 \u06cc\u0627\u0628\u062f. \u062f\u0631 \u0628\u0639\u0636\u06cc \u0645\u0648\u0627\u0631\u062f\u060c \u0645\u0645\u06a9\u0646 \u0627\u0633\u062a \u062d\u062a\u06cc \u0633\u0627\u06cc\u062a \u0634\u0645\u0627 \u0627\u0632 \u0646\u062a\u0627\u06cc\u062c \u062c\u0633\u062a\u062c\u0648 \u062d\u0630\u0641 \u0634\u0648\u062f. \u0627\u06af\u0631 \u0641\u06a9\u0631 \u0645\u06cc\u200c\u06a9\u0646\u06cc\u062f \u0633\u0627\u06cc\u062a \u0634\u0645\u0627 \u062a\u0648\u0633\u0637 \u067e\u0646\u06af\u0648\u0626\u0646 \u062c\u0631\u06cc\u0645\u0647 \u0634\u062f\u0647 \u0627\u0633\u062a\u060c \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u06cc\u062f \u0628\u0627 \u06af\u0648\u06af\u0644 \u062a\u0645\u0627\u0633 \u0628\u06af\u06cc\u0631\u06cc\u062f \u062a\u0627 \u0627\u0632 \u0648\u0636\u0639\u06cc\u062a \u0633\u0627\u06cc\u062a \u062e\u0648\u062f \u0645\u0637\u0644\u0639 \u0634\u0648\u06cc\u062f. \u0647\u0645\u0686\u0646\u06cc\u0646 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u06cc\u062f \u0627\u0632 \u06cc\u06a9 \u0645\u062a\u062e\u0635\u0635 \u0633\u0626\u0648 \u06a9\u0645\u06a9 \u0628\u06af\u06cc\u0631\u06cc\u062f \u062a\u0627 \u0633\u0627\u06cc\u062a \u0634\u0645\u0627 \u0631\u0627 \u0628\u0647\u0628\u0648\u062f \u0628\u0628\u062e\u0634\u062f.<\/p>\n<h2 style=\"text-align: justify\"><span class=\"ez-toc-section\" id=\"%D8%AC%D9%85%D8%B9%D8%A8%D9%86%D8%AF%DB%8C\"><\/span><span style=\"font-size: 14pt;color: #003366\">\u062c\u0645\u0639\u0628\u0646\u062f\u06cc<\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p style=\"text-align: justify\">\u0627\u0644\u06af\u0631\u06cc\u062a\u0645 \u067e\u0646\u06af\u0648\u0626\u0646 \u06cc\u06a9\u06cc \u0627\u0632 \u0627\u0644\u06af\u0648\u0631\u06cc\u062a\u0645\u200c\u0647\u0627\u06cc \u0645\u0647\u0645 \u06af\u0648\u06af\u0644 \u0627\u0633\u062a \u06a9\u0647 \u0628\u0647 \u062d\u0641\u0638 \u0631\u062a\u0628\u0647\u200c\u0628\u0646\u062f\u06cc \u0637\u0628\u06cc\u0639\u06cc \u0648 \u0628\u0627\u06a9\u06cc\u0641\u06cc\u062a \u0633\u0627\u06cc\u062a\u200c\u0647\u0627 \u06a9\u0645\u06a9 \u0645\u06cc\u200c\u06a9\u0646\u062f. \u0628\u0627 \u067e\u06cc\u0631\u0648\u06cc \u0627\u0632 \u0646\u06a9\u0627\u062a \u0630\u06a9\u0631 \u0634\u062f\u0647 \u062f\u0631 \u0627\u06cc\u0646 \u0645\u0642\u0627\u0644\u0647\u060c \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u06cc\u062f \u0627\u0632 \u062c\u0631\u06cc\u0645\u0647 \u0634\u062f\u0646 \u062a\u0648\u0633\u0637 \u067e\u0646\u06af\u0648\u0626\u0646 \u062c\u0644\u0648\u06af\u06cc\u0631\u06cc \u06a9\u0646\u06cc\u062f \u0648 \u0631\u062a\u0628\u0647\u200c\u0628\u0646\u062f\u06cc \u0637\u0628\u06cc\u0639\u06cc \u0633\u0627\u06cc\u062a \u062e\u0648\u062f \u0631\u0627 \u0628\u0647\u0628\u0648\u062f \u0628\u0628\u062e\u0634\u06cc\u062f.<\/p>\n<p style=\"text-align: justify\">\n","protected":false},"excerpt":{"rendered":"<p>\u0645\u0642\u062f\u0645\u0647 \u0627\u0644\u06af\u0631\u06cc\u062a\u0645 \u067e\u0646\u06af\u0648\u0626\u0646 \u06cc\u06a9\u06cc \u0627\u0632 \u0627\u0644\u06af\u0648\u0631\u06cc\u062a\u0645\u200c\u0647\u0627\u06cc \u0645\u0647\u0645 \u0645\u0648\u062a\u0648\u0631 \u062c\u0633\u062a\u062c\u0648\u06cc \u06af\u0648\u06af\u0644 \u0627\u0633\u062a \u06a9\u0647 \u062f\u0631 \u0633\u0627\u0644 2012 \u0645\u0639\u0631\u0641\u06cc \u0634\u062f. \u0627\u06cc\u0646 \u0627\u0644\u06af\u0648\u0631\u06cc\u062a\u0645 \u0628\u0647 \u0645\u0646\u0638\u0648\u0631 \u0645\u0642\u0627\u0628\u0644\u0647 \u0628\u0627 \u0633\u0627\u06cc\u062a\u200c\u0647\u0627\u06cc\u06cc \u06a9\u0647 \u0627\u0632 \u0631\u0648\u0634\u200c\u0647\u0627\u06cc \u063a\u06cc\u0631\u0637\u0628\u06cc\u0639\u06cc \u0628\u0631\u0627\u06cc \u0628\u0647\u0628\u0648\u062f \u0631\u062a\u0628\u0647\u200c\u0628\u0646\u062f\u06cc \u062e\u0648\u062f \u062f\u0631 \u0646\u062a\u0627\u06cc\u062c \u062c\u0633\u062a\u062c\u0648 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0645\u06cc\u200c\u06a9\u0646\u0646\u062f\u060c \u0637\u0631\u0627\u062d\u06cc \u0634\u062f\u0647 \u0627\u0633\u062a. \u067e\u0646\u06af\u0648\u0626\u0646 \u0628\u0647\u200c\u0637\u0648\u0631 \u062e\u0627\u0635 \u0628\u0647 \u0644\u06cc\u0646\u06a9\u200c\u0647\u0627\u06cc \u0627\u0633\u067e\u0645 \u062a\u0648\u062c\u0647 \u062f\u0627\u0631\u062f \u0648 \u0633\u0627\u06cc\u062a\u200c\u0647\u0627\u06cc\u06cc \u06a9\u0647 \u0631\u062a\u0628\u0647\u200c\u0628\u0646\u062f\u06cc \u0622\u0646\u0647\u0627 \u0628\u0627 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 &hellip;<\/p>\n","protected":false},"author":2,"featured_media":1620,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24],"tags":[],"class_list":["post-1614","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-website-seo-training"],"_links":{"self":[{"href":"https:\/\/webmehr.com\/blog\/wp-json\/wp\/v2\/posts\/1614","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/webmehr.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/webmehr.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/webmehr.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/webmehr.com\/blog\/wp-json\/wp\/v2\/comments?post=1614"}],"version-history":[{"count":1,"href":"https:\/\/webmehr.com\/blog\/wp-json\/wp\/v2\/posts\/1614\/revisions"}],"predecessor-version":[{"id":1621,"href":"https:\/\/webmehr.com\/blog\/wp-json\/wp\/v2\/posts\/1614\/revisions\/1621"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/webmehr.com\/blog\/wp-json\/wp\/v2\/media\/1620"}],"wp:attachment":[{"href":"https:\/\/webmehr.com\/blog\/wp-json\/wp\/v2\/media?parent=1614"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/webmehr.com\/blog\/wp-json\/wp\/v2\/categories?post=1614"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/webmehr.com\/blog\/wp-json\/wp\/v2\/tags?post=1614"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}